{"id":39125,"date":"2023-10-12T19:48:01","date_gmt":"2023-10-12T23:48:01","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39125"},"modified":"2024-08-10T12:54:47","modified_gmt":"2024-08-10T16:54:47","slug":"impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/","title":{"rendered":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG"},"content":{"rendered":"\n<p>Nosso mundo est\u00e1 passando por grandes mudan\u00e7as. As pessoas est\u00e3o come\u00e7ando a se preocupar mais com o cuidado com o nosso planeta, tratando todos de forma justa e fazendo neg\u00f3cios corretamente. Essas ideias importantes t\u00eam um nome: ESG, que significa ambiental, social e de governan\u00e7a. Vamos explorar por que o ESG \u00e9 t\u00e3o importante no mundo de hoje.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 ESG e o movimento ESG?<\/h2>\n\n\n\n<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/AkbGz3CYvqE?si=KHSn0PDc6JUQS_OB\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<p><a href=\"https:\/\/corporatefinanceinstitute.com\/resources\/esg\/esg-environmental-social-governance\/\">ESG<\/a>, que significa Environmental, Social, and Governance (Ambiental, Social e Governan\u00e7a), \u00e9 um conjunto de crit\u00e9rios importantes para julgar o desempenho de uma empresa em tr\u00eas \u00e1reas principais. Essas \u00e1reas s\u00e3o o meio ambiente, a forma como ela trata as pessoas e como \u00e9 administrada. Vamos examinar o que significa ESG e por que ele \u00e9 importante hoje.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESG: Detalhando<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"731\" src=\"https:\/\/sustainablereview.com\/\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1-1024x731.jpg\" alt=\"ESG: Breaking It Down\" class=\"wp-image-30074\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1-1024x731.jpg 1024w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1-300x214.jpg 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1-768x549.jpg 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1-45x32.jpg 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/naem-2021-webinar-banner-developing-and-sustaining-a-culture-of-health-for-business-coh4b-linking-with-esg-reporting-standard-redinger-700x500-1.jpg 1400w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:12px\"><strong>Cr\u00e9dito da imagem: Naem.org<\/strong><\/p>\n\n\n\n<p>Imagine que voc\u00ea tenha um boletim de notas de uma empresa, como o boletim que voc\u00ea recebe na escola. Esse boletim, chamado ESG, verifica tr\u00eas coisas essenciais:<\/p>\n\n\n\n<p><strong>1. Ambiental:<\/strong> ao discutir fatores ambientais, examinamos como uma empresa afeta o mundo ao nosso redor. Isso inclui aspectos como a quantidade de gases de efeito estufa que ela libera, como cuida da natureza e como est\u00e1 preparada para lidar com os problemas causados pelas mudan\u00e7as clim\u00e1ticas, como enchentes e inc\u00eandios.<\/p>\n\n\n\n<p>Trata-se de como a empresa trata o planeta. \u00c9 como se voc\u00ea perguntasse: &#8220;A empresa est\u00e1 cuidando da natureza?&#8221; Por exemplo, ela est\u00e1 usando energia limpa, reduzindo o desperd\u00edcio e n\u00e3o poluindo o ar ou a \u00e1gua?<\/p>\n\n\n\n<p><strong>2. Social: <\/strong>O lado social do ESG tem a ver com a forma como a empresa trata as pessoas e as comunidades. N\u00e3o se trata apenas de como ela trata seus funcion\u00e1rios, mas tamb\u00e9m de como ela afeta seus locais de trabalho. Por exemplo, ela paga sal\u00e1rios justos e garante que seus funcion\u00e1rios estejam felizes? O ESG tamb\u00e9m se preocupa com as pessoas em suas cadeias de suprimentos, especialmente em pa\u00edses onde as regras ambientais e trabalhistas podem n\u00e3o ser t\u00e3o r\u00edgidas.<\/p>\n\n\n\n<p>Essa parte tem tudo a ver com as pessoas. \u00c9 como perguntar: &#8220;A empresa est\u00e1 tratando todos de forma justa e gentil?&#8221; Isso inclui funcion\u00e1rios, clientes e pessoas das comunidades da empresa. Os trabalhadores s\u00e3o bem pagos e tratados com respeito? A empresa retribui \u00e0 comunidade?<\/p>\n\n\n\n<p><strong>3. Governan\u00e7a: <\/strong>a governan\u00e7a corporativa \u00e9 como o livro de regras da empresa. Os especialistas em ESG querem saber se os l\u00edderes da empresa seguem as regras e fazem o que \u00e9 adequado para todos. Eles verificam se as metas dos l\u00edderes correspondem ao que os propriet\u00e1rios da empresa querem, se os propriet\u00e1rios t\u00eam voz ativa e se h\u00e1 regras claras para garantir que todos sejam honestos e abertos.<\/p>\n\n\n\n<p>Pense na governan\u00e7a como as regras e a lideran\u00e7a da empresa. \u00c9 como se voc\u00ea perguntasse: &#8220;A empresa est\u00e1 seguindo as regras e sendo honesta?&#8221; Boa governan\u00e7a significa que os l\u00edderes s\u00e3o transparentes e respons\u00e1veis e tomam decis\u00f5es que beneficiam a todos, n\u00e3o apenas alguns.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Por que o ESG \u00e9 t\u00e3o importante agora?<\/strong><\/h3>\n\n\n\n<p>A <a href=\"https:\/\/sustainablereview.com\/pt-br\/os-5-melhores-cursos-e-certificacoes-da-esg-para-profissionais\/\">import\u00e2ncia do ESG<\/a> (Ambiental, Social e de Governan\u00e7a) est\u00e1 aumentando, e h\u00e1 raz\u00f5es convincentes por tr\u00e1s de sua crescente import\u00e2ncia:<\/p>\n\n\n\n<p><strong>Enfrentar os desafios globais<\/strong>: Nosso planeta est\u00e1 enfrentando desafios cr\u00edticos, como a mudan\u00e7a clim\u00e1tica e o esgotamento de recursos vitais. Essas preocupa\u00e7\u00f5es geraram alarme em todo o mundo, aumentando as expectativas de que as empresas contribuam ativamente para resolver esses problemas globais.<\/p>\n\n\n\n<p><strong>Adotar uma vis\u00e3o de longo prazo<\/strong>: N\u00e3o se trata mais apenas de lucros a curto prazo. As pessoas perceberam que, para que uma empresa tenha sucesso a longo prazo, ela tamb\u00e9m deve ser uma for\u00e7a para o bem. Os princ\u00edpios de ESG orientam as empresas em dire\u00e7\u00e3o \u00e0 sustentabilidade, garantindo que elas sobrevivam e prosperem para as gera\u00e7\u00f5es futuras.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Exemplos de ESG em a\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p>Vamos explorar como os princ\u00edpios de ESG ganham vida por meio de exemplos concretos:<\/p>\n\n\n\n<p><strong>Ambiental<\/strong>: Considere uma empresa como a <a href=\"https:\/\/hbr.org\/2020\/02\/lessons-from-teslas-approach-to-innovation\">Tesla<\/a>, famosa por seus carros el\u00e9tricos. O compromisso da Tesla com o transporte sustent\u00e1vel ajuda a reduzir a polui\u00e7\u00e3o do ar e a combater as mudan\u00e7as clim\u00e1ticas. Ao fabricar ve\u00edculos el\u00e9tricos, ela contribui para um ambiente mais limpo e saud\u00e1vel.<\/p>\n\n\n\n<p><strong>Social<\/strong>: <a href=\"https:\/\/stories.starbucks.com\/press\/2021\/starbucks-commitment-to-environmental-social-and-governance-disclosures\/\">A Starbucks<\/a> \u00e9 outro excelente exemplo de ESG em a\u00e7\u00e3o. Desde 2001, a empresa publica atualiza\u00e7\u00f5es anuais sobre seu desempenho relacionado a fatores ambientais, sociais e de governan\u00e7a (ESG). A partir de 2021, a Starbucks se comprometeu a integrar os padr\u00f5es de relat\u00f3rio SASB ESG em seu Relat\u00f3rio de Impacto Ambiental e Social Global anual.<\/p>\n\n\n\n<p>A gigante do caf\u00e9 \u00e9 conhecida por suas pol\u00edticas favor\u00e1veis aos funcion\u00e1rios, incluindo seguro de sa\u00fade e apoio educacional. A Starbucks se dedica a auditorias transparentes de terceiros e a divulga\u00e7\u00f5es cont\u00ednuas de seu impacto social e ambiental global. Al\u00e9m disso, a Starbucks apoia ativamente os produtores de caf\u00e9 em todo o mundo, garantindo sal\u00e1rios justos e pr\u00e1ticas agr\u00edcolas \u00e9ticas. Isso demonstra seu compromisso com a responsabilidade social e o bem-estar da comunidade.<\/p>\n\n\n\n<p><strong>Governan\u00e7a<\/strong>: <a href=\"https:\/\/www.apple.com\/compliance\/\">A Apple Inc<\/a>. estabelece um padr\u00e3o elevado em termos de pr\u00e1ticas de governan\u00e7a. Os relat\u00f3rios financeiros transparentes e a lideran\u00e7a \u00e9tica da empresa conquistam a confian\u00e7a dos acionistas e investidores. O compromisso da Apple com uma s\u00f3lida governan\u00e7a corporativa garante a responsabilidade, a transpar\u00eancia e a tomada de decis\u00f5es respons\u00e1veis.<\/p>\n\n\n\n<p>Esses exemplos do mundo real destacam a aplica\u00e7\u00e3o pr\u00e1tica dos princ\u00edpios de ESG. O movimento ESG n\u00e3o visa apenas ao lucro; trata-se de empresas que impactam positivamente o mundo, abordando quest\u00f5es ambientais, sociais e de governan\u00e7a e, ao mesmo tempo, prosperando no processo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Investimento em ESG: Uma nova abordagem para a sustentabilidade<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"760\" src=\"https:\/\/sustainablereview.com\/\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0-1024x760.png\" alt=\"Institutions embrace ESG investing\" class=\"wp-image-30073\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0-1024x760.png 1024w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0-300x223.png 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0-768x570.png 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0-45x33.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/0_H1fbu0jvhph2rgI0.png 1272w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Como o investimento em ESG difere do investimento tradicional?<\/h3>\n\n\n\n<p>O investimento em ESG difere do investimento convencional ao integrar fatores de ESG \u00e0s decis\u00f5es de investimento. Enquanto o investimento tradicional se concentra principalmente em retornos financeiros, o investimento em ESG leva em conta considera\u00e7\u00f5es mais amplas, inclusive o impacto social e ambiental de uma empresa. Seu objetivo \u00e9 gerar retornos financeiros sustent\u00e1veis e, ao mesmo tempo, promover mudan\u00e7as positivas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quais s\u00e3o os fatores cr\u00edticos considerados no investimento em ESG?<\/h3>\n\n\n\n<p>O investimento em ESG considera v\u00e1rios fatores, inclusive as emiss\u00f5es de carbono, a diversidade e a inclus\u00e3o, as pr\u00e1ticas trabalhistas, a seguran\u00e7a do produto e a gest\u00e3o da cadeia de suprimentos de uma empresa. Esses fatores fornecem percep\u00e7\u00f5es sobre a sustentabilidade e as pr\u00e1ticas \u00e9ticas de uma empresa, orientando as decis\u00f5es de investimento com base na cria\u00e7\u00e3o de valor de longo prazo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Explorando o crescimento dos fundos ESG<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"620\" src=\"https:\/\/sustainablereview.com\/\/wp-content\/uploads\/2023\/10\/image-15-1024x620-1.png\" alt=\"Exploring the growth of ESG funds\" class=\"wp-image-30072\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/image-15-1024x620-1.png 1024w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/image-15-1024x620-1-300x182.png 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/image-15-1024x620-1-768x465.png 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/image-15-1024x620-1-45x27.png 45w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure>\n\n\n\n<p>Nos \u00faltimos anos, houve um crescimento significativo nos fundos ESG. Esses fundos alocam capital especificamente para empresas com forte desempenho em ESG. De acordo com a Morningstar, <a href=\"https:\/\/www.reuters.com\/article\/us-global-funds-sustainable-idUSKBN29X2NM\">os fundos sustent\u00e1veis globais<\/a> atra\u00edram quase US$ 1,7 trilh\u00e3o em ativos sob gest\u00e3o at\u00e9 o final de 2020, refletindo o crescente interesse em investimentos em ESG.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O papel da governan\u00e7a no movimento ESG<\/h2>\n\n\n\n<p>O investimento em ESG n\u00e3o \u00e9 a maneira t\u00edpica de voc\u00ea investir dinheiro. \u00c9 um pouco diferente, e aqui est\u00e1 o porqu\u00ea:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Investimento ESG versus investimento tradicional<\/strong><\/h3>\n\n\n\n<p>No investimento tradicional, o foco principal \u00e9 ganhar dinheiro. As pessoas investem seu dinheiro para obter mais dinheiro de volta, e isso \u00e9 tudo. Mas o investimento ESG acrescenta algo a mais \u00e0 mistura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O ESG leva em conta o cen\u00e1rio mais amplo<\/strong><\/h3>\n\n\n\n<p>ESG, que significa Environmental, Social, and Governance (Ambiental, Social e de Governan\u00e7a), analisa o panorama geral. Sim, ainda se trata de ganhar dinheiro, mas tamb\u00e9m de impactar positivamente o mundo. Assim, voc\u00ea pergunta: &#8220;Esta empresa est\u00e1 ganhando dinheiro de uma forma que seja boa para o meio ambiente e para as pessoas?&#8221;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fatores-chave do investimento em ESG<\/strong><\/h3>\n\n\n\n<p>Quando os investidores em ESG decidem onde colocar seu dinheiro, eles analisam alguns aspectos essenciais:<\/p>\n\n\n\n<ol>\n<li><strong>Emiss\u00f5es de carbono:<\/strong> Isso significa a quantidade de polui\u00e7\u00e3o que uma empresa gera. As empresas que poluem muito podem n\u00e3o ser adequadas para o meio ambiente, e isso n\u00e3o \u00e9 bom para o longo prazo.<\/li>\n\n\n\n<li><strong>Diversidade e inclus\u00e3o:<\/strong> Os investidores de ESG querem ver uma mistura de pessoas trabalhando em uma empresa. Quando uma empresa tem trabalhadores de diferentes origens, isso geralmente significa que eles t\u00eam perspectivas diferentes, o que pode ser bom para os neg\u00f3cios.<\/li>\n\n\n\n<li><strong>Pr\u00e1ticas trabalhistas:<\/strong> Trata-se de como a empresa trata seus funcion\u00e1rios. Os investidores ESG gostam de empresas que tratam os funcion\u00e1rios de forma justa, pagam bem e os mant\u00eam seguros no trabalho.<\/li>\n\n\n\n<li><strong>Seguran\u00e7a do produto:<\/strong> Ningu\u00e9m quer comprar produtos perigosos. Os investidores de ESG verificam se as empresas vendem produtos que n\u00e3o prejudicam as pessoas.<\/li>\n\n\n\n<li><strong>Gest\u00e3o da cadeia de suprimentos:<\/strong> Os investidores em ESG analisam como as empresas obt\u00eam seus materiais e fabricam seus produtos. Eles querem garantir que isso seja feito de uma forma que seja boa para o meio ambiente e justa para as pessoas envolvidas.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Os desafios e as oportunidades do ESG<\/h2>\n\n\n\n<p>Algumas pessoas t\u00eam d\u00favidas sobre o movimento ESG, portanto, \u00e9 essencial que voc\u00ea as analise de perto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como lidar com as cr\u00edticas ao movimento ESG<\/h3>\n\n\n\n<p>O movimento de ESG tem <a href=\"https:\/\/sustainablereview.com\/pt-br\/o-problema-com-os-fundos-esg-e-como-corrigi-los\/\">enfrentado cr\u00edticas<\/a>, incluindo preocupa\u00e7\u00f5es sobre greenwashing, que se refere a empresas que fazem afirma\u00e7\u00f5es falsas ou exageradas sobre suas pr\u00e1ticas de ESG. Para lidar com essas cr\u00edticas, o desenvolvimento de normas e regulamentos robustos de ESG \u00e9 fundamental para garantir a credibilidade e a integridade do movimento de ESG.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Explorando os poss\u00edveis retornos financeiros do investimento em ESG<\/h3>\n\n\n\n<p>Ao contr\u00e1rio da concep\u00e7\u00e3o err\u00f4nea de que o investimento em ESG sacrifica os retornos financeiros, as evid\u00eancias sugerem que as empresas com forte desempenho em ESG geralmente superam seus pares no longo prazo. Muitos estudos mostraram uma correla\u00e7\u00e3o positiva entre pr\u00e1ticas s\u00f3lidas de ESG e desempenho financeiro, indicando poss\u00edveis retornos financeiros no investimento em ESG.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O papel dos servi\u00e7os financeiros na promo\u00e7\u00e3o da ado\u00e7\u00e3o de ESG<\/h3>\n\n\n\n<p>Os servi\u00e7os financeiros, incluindo gestores de ativos e fundos de pens\u00e3o, desempenham um papel significativo na promo\u00e7\u00e3o da ado\u00e7\u00e3o de ESG. Ao integrar considera\u00e7\u00f5es de ESG em suas estrat\u00e9gias de investimento, essas institui\u00e7\u00f5es influenciam as empresas a priorizar os fatores de ESG. A demanda por investimentos em ESG por parte de investidores institucionais acelera ainda mais a integra\u00e7\u00e3o do ESG no cen\u00e1rio de investimentos convencionais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Olhando para o futuro: O futuro do ESG<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Prevendo o impacto do ESG em 2022 e nos anos seguintes<\/h3>\n\n\n\n<p>Espera-se que o impacto do ESG continue a crescer em 2022 e nos anos seguintes. \u00c0 medida que mais empresas reconhecem a import\u00e2ncia do ESG, podemos prever uma maior ado\u00e7\u00e3o de pr\u00e1ticas sustent\u00e1veis, melhores padr\u00f5es de governan\u00e7a e um foco maior em fatores sociais e ambientais. O ESG se tornar\u00e1 uma for\u00e7a motriz para mudan\u00e7as positivas em v\u00e1rios setores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O papel das partes interessadas em moldar o futuro do ESG<\/h3>\n\n\n\n<p>As partes interessadas, incluindo investidores, consumidores, funcion\u00e1rios e reguladores, desempenhar\u00e3o um papel fundamental na forma\u00e7\u00e3o do futuro do ESG. Sua crescente demanda por pr\u00e1ticas sustent\u00e1veis e respons\u00e1veis far\u00e1 com que as empresas adotem o ESG como um imperativo estrat\u00e9gico, levando a um cen\u00e1rio de neg\u00f3cios mais sustent\u00e1vel e equitativo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A import\u00e2ncia da inova\u00e7\u00e3o cont\u00ednua nas m\u00e9tricas de ESG<\/h3>\n\n\n\n<p>A inova\u00e7\u00e3o cont\u00ednua nas m\u00e9tricas de ESG \u00e9 essencial para aumentar a efic\u00e1cia da avalia\u00e7\u00e3o e dos relat\u00f3rios de ESG. \u00c0 medida que o cen\u00e1rio de ESG evolui, novas m\u00e9tricas e estruturas ser\u00e3o desenvolvidas para capturar uma gama mais ampla de fatores de ESG e fornecer percep\u00e7\u00f5es mais precisas sobre o desempenho de sustentabilidade de uma empresa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perguntas frequentes<\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1697154383225\"><strong class=\"schema-faq-question\">O que \u00e9 ESG?<\/strong> <p class=\"schema-faq-answer\">ESG significa Ambiental, Social e de Governan\u00e7a. \u00c9 uma estrutura para avaliar a sustentabilidade e as pr\u00e1ticas \u00e9ticas de uma empresa.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154388477\">O <strong class=\"schema-faq-question\">que \u00e9 o movimento ESG?<\/strong> <p class=\"schema-faq-answer\">O movimento ESG refere-se ao foco crescente em sustentabilidade e responsabilidade social nas pr\u00e1ticas de neg\u00f3cios e investimentos.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154392740\"><strong class=\"schema-faq-question\">Como o movimento ESG afeta as empresas globais?<\/strong> <p class=\"schema-faq-answer\">O movimento ESG leva as empresas a adotar pr\u00e1ticas sustent\u00e1veis, melhorar os resultados sociais e ambientais e aprimorar a governan\u00e7a corporativa.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154400894\">O <strong class=\"schema-faq-question\">que s\u00e3o crit\u00e9rios de ESG?<\/strong> <p class=\"schema-faq-answer\">Os crit\u00e9rios de ESG s\u00e3o os fatores usados para avaliar o desempenho ambiental, social e de governan\u00e7a de uma empresa. Esses crit\u00e9rios variam entre as ag\u00eancias de classifica\u00e7\u00e3o e os investidores.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154406765\"><strong class=\"schema-faq-question\">O que s\u00e3o fundos ESG?<\/strong> <p class=\"schema-faq-answer\">Os fundos ESG s\u00e3o fundos de investimento que priorizam empresas com pr\u00e1ticas ambientais, sociais e de governan\u00e7a substanciais.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154413587\">O <strong class=\"schema-faq-question\">que \u00e9 o movimento anti-ESG?<\/strong> <p class=\"schema-faq-answer\">O movimento anti-ESG \u00e9 um grupo que se op\u00f5e \u00e0s ideias e aos princ\u00edpios do ESG, argumentando que ele impede o crescimento econ\u00f4mico e o valor para os acionistas.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154422576\">O <strong class=\"schema-faq-question\">que s\u00e3o padr\u00f5es de ESG?<\/strong> <p class=\"schema-faq-answer\">Os padr\u00f5es de ESG s\u00e3o as diretrizes e os padr\u00f5es de refer\u00eancia usados para avaliar e comparar o desempenho de ESG das empresas.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154430740\"><strong class=\"schema-faq-question\">O que s\u00e3o ag\u00eancias de classifica\u00e7\u00e3o de ESG?<\/strong> <p class=\"schema-faq-answer\">As ag\u00eancias de classifica\u00e7\u00e3o de ESG s\u00e3o organiza\u00e7\u00f5es que avaliam e classificam o desempenho de ESG das empresas. Elas fornecem aos investidores dados e an\u00e1lises para que voc\u00ea possa tomar decis\u00f5es informadas.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154437546\"><strong class=\"schema-faq-question\">O que \u00e9 divulga\u00e7\u00e3o de ESG?<\/strong> <p class=\"schema-faq-answer\">R: A divulga\u00e7\u00e3o de ESG refere-se \u00e0s empresas que compartilham abertamente informa\u00e7\u00f5es sobre seu desempenho ambiental, social e de governan\u00e7a.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1697154445038\"><strong class=\"schema-faq-question\">Qual \u00e9 o papel das ag\u00eancias de classifica\u00e7\u00e3o no investimento em ESG?<\/strong> <p class=\"schema-faq-answer\">R: As ag\u00eancias de classifica\u00e7\u00e3o desempenham um papel fundamental no investimento em ESG ao avaliar objetivamente o desempenho de ESG das empresas, o que ajuda os investidores a tomar decis\u00f5es informadas.<\/p> <\/div> <\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Para concluir, nossa explora\u00e7\u00e3o do movimento ESG (ambiental, social e de governan\u00e7a) revela seu profundo impacto global. O ESG destaca a necessidade de considerar fatores ambientais, sociais e de governan\u00e7a na tomada de decis\u00f5es, promovendo pr\u00e1ticas \u00e9ticas e sustent\u00e1veis juntamente com o sucesso financeiro.<\/p>\n\n\n\n<p>A governan\u00e7a, um elemento essencial do ESG, garante a responsabilidade e a transpar\u00eancia dentro das organiza\u00e7\u00f5es e por meio de pol\u00edticas governamentais. A influ\u00eancia do movimento ESG nas pr\u00e1ticas de neg\u00f3cios e investimentos est\u00e1 crescendo, enfatizando o comportamento respons\u00e1vel.<\/p>\n\n\n\n<p>O ESG alinha o lucro com o bem-estar planet\u00e1rio e social, abordando os desafios globais por meio de a\u00e7\u00f5es coletivas. A administra\u00e7\u00e3o ambiental, a responsabilidade social e a governan\u00e7a eficaz s\u00e3o agora essenciais, guiando-nos em dire\u00e7\u00e3o a um mundo onde o lucro coexiste com prop\u00f3sito e compromisso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p>Conhe\u00e7a o movimento transformador de ESG, seu impacto global e o papel da governan\u00e7a na condu\u00e7\u00e3o da mudan\u00e7a. Explore o poder do ESG para um futuro sustent\u00e1vel.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":1502,"featured_media":30075,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3091,3097],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a o movimento transformador de ESG, seu impacto global e o papel da governan\u00e7a na condu\u00e7\u00e3o da mudan\u00e7a. Explore o poder do ESG para um futuro sustent\u00e1vel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-12T23:48:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T16:54:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raf Chomsky\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raf Chomsky\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\"},\"author\":{\"name\":\"Raf Chomsky\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339\"},\"headline\":\"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG\",\"datePublished\":\"2023-10-12T23:48:01+00:00\",\"dateModified\":\"2024-08-10T16:54:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\"},\"wordCount\":2557,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg\",\"articleSection\":[\"Energia e meio ambiente\",\"Planeta\"],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\",\"name\":\"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg\",\"datePublished\":\"2023-10-12T23:48:01+00:00\",\"dateModified\":\"2024-08-10T16:54:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546\"},{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038\"}],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg\",\"width\":900,\"height\":600,\"caption\":\"ESG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339\",\"name\":\"Raf Chomsky\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632\",\"caption\":\"Raf Chomsky\"},\"description\":\"Dedicated author deeply engaged in sustainability issues. My writing focuses on practical, impactful solutions and communicates the urgency of environmental responsibility. With a commitment to raising awareness, I aim to inform and inspire readers to embrace sustainable practices in their daily lives.\",\"sameAs\":[\"https:\/\/sustainablereview.com\/\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/nonagency\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225\",\"position\":1,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225\",\"name\":\"What is ESG?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"ESG stands for Environmental, Social, and Governance. It is a framework to evaluate a company's sustainability and ethical practices.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477\",\"position\":2,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477\",\"name\":\"What is the ESG movement?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"The ESG movement refers to the growing focus on sustainability and social responsibility in business and investing practices.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740\",\"position\":3,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740\",\"name\":\"How does the ESG movement impact global businesses?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"The ESG movement drives businesses to adopt sustainable practices, improve social and environmental outcomes, and enhance corporate governance.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894\",\"position\":4,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894\",\"name\":\"What are ESG criteria?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"ESG criteria are the factors used to assess a company's environmental, social, and governance performance. These criteria vary among rating agencies and investors.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765\",\"position\":5,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765\",\"name\":\"What are ESG funds?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"ESG funds are investment funds that prioritize companies with substantial environmental, social, and governance practices.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587\",\"position\":6,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587\",\"name\":\"What is the anti-ESG movement?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"The anti-ESG movement is a group that opposes the ideas and principles of ESG, arguing that it hinders economic growth and shareholder value.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576\",\"position\":7,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576\",\"name\":\"What are ESG standards?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"ESG standards are the guidelines and benchmarks used to evaluate and compare companies' ESG performance.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740\",\"position\":8,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740\",\"name\":\"What are ESG rating agencies?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"ESG rating agencies are organizations that assess and rate the ESG performance of companies. They provide investors with data and analysis to make informed decisions.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546\",\"position\":9,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546\",\"name\":\"What is ESG disclosure?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A: ESG disclosure refers to companies openly sharing information about their environmental, social, and governance performance.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038\",\"position\":10,\"url\":\"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038\",\"name\":\"What is the role of rating agencies in ESG investing?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A: Rating agencies play a critical role in ESG investing by objectively assessing companies' ESG performance, which helps investors make informed decisions.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/","og_locale":"pt_BR","og_type":"article","og_title":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review","og_description":"Conhe\u00e7a o movimento transformador de ESG, seu impacto global e o papel da governan\u00e7a na condu\u00e7\u00e3o da mudan\u00e7a. Explore o poder do ESG para um futuro sustent\u00e1vel.","og_url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/","og_site_name":"Sustainable Review","article_published_time":"2023-10-12T23:48:01+00:00","article_modified_time":"2024-08-10T16:54:47+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg","type":"image\/jpeg"}],"author":"Raf Chomsky","twitter_card":"summary_large_image","twitter_creator":"@sustainreview","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Raf Chomsky","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/"},"author":{"name":"Raf Chomsky","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339"},"headline":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG","datePublished":"2023-10-12T23:48:01+00:00","dateModified":"2024-08-10T16:54:47+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/"},"wordCount":2557,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg","articleSection":["Energia e meio ambiente","Planeta"],"inLanguage":"pt-BR"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/","url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/","name":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg","datePublished":"2023-10-12T23:48:01+00:00","dateModified":"2024-08-10T16:54:47+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546"},{"@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038"}],"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/10\/R.jpg","width":900,"height":600,"caption":"ESG"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Impulsionando a mudan\u00e7a: Explorando o impacto global do movimento ESG"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339","name":"Raf Chomsky","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632","caption":"Raf Chomsky"},"description":"Dedicated author deeply engaged in sustainability issues. My writing focuses on practical, impactful solutions and communicates the urgency of environmental responsibility. With a commitment to raising awareness, I aim to inform and inspire readers to embrace sustainable practices in their daily lives.","sameAs":["https:\/\/sustainablereview.com\/"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/nonagency\/"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225","position":1,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154383225","name":"What is ESG?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"ESG stands for Environmental, Social, and Governance. It is a framework to evaluate a company's sustainability and ethical practices.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477","position":2,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154388477","name":"What is the ESG movement?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"The ESG movement refers to the growing focus on sustainability and social responsibility in business and investing practices.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740","position":3,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154392740","name":"How does the ESG movement impact global businesses?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"The ESG movement drives businesses to adopt sustainable practices, improve social and environmental outcomes, and enhance corporate governance.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894","position":4,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154400894","name":"What are ESG criteria?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"ESG criteria are the factors used to assess a company's environmental, social, and governance performance. These criteria vary among rating agencies and investors.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765","position":5,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154406765","name":"What are ESG funds?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"ESG funds are investment funds that prioritize companies with substantial environmental, social, and governance practices.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587","position":6,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154413587","name":"What is the anti-ESG movement?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"The anti-ESG movement is a group that opposes the ideas and principles of ESG, arguing that it hinders economic growth and shareholder value.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576","position":7,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154422576","name":"What are ESG standards?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"ESG standards are the guidelines and benchmarks used to evaluate and compare companies' ESG performance.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740","position":8,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154430740","name":"What are ESG rating agencies?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"ESG rating agencies are organizations that assess and rate the ESG performance of companies. They provide investors with data and analysis to make informed decisions.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546","position":9,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154437546","name":"What is ESG disclosure?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A: ESG disclosure refers to companies openly sharing information about their environmental, social, and governance performance.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"},{"@type":"Question","@id":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038","position":10,"url":"https:\/\/sustainablereview.com\/pt-br\/impulsionando-a-mudanca-explorando-o-impacto-global-do-movimento-esg\/#faq-question-1697154445038","name":"What is the role of rating agencies in ESG investing?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"A: Rating agencies play a critical role in ESG investing by objectively assessing companies' ESG performance, which helps investors make informed decisions.","inLanguage":"pt-BR"},"inLanguage":"pt-BR"}]}},"wpml_translations":{"en":"30070","pl":"60430","pt-br":"39125"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39125"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/1502"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39125"}],"version-history":[{"count":3,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39125\/revisions"}],"predecessor-version":[{"id":62265,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39125\/revisions\/62265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/30075"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}