{"id":39192,"date":"2023-08-24T15:53:01","date_gmt":"2023-08-24T19:53:01","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39192"},"modified":"2024-08-10T12:57:43","modified_gmt":"2024-08-10T16:57:43","slug":"google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/","title":{"rendered":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade"},"content":{"rendered":"\n<p>Um velho ditado ainda \u00e9 verdadeiro em rela\u00e7\u00e3o ao cuidado com o meio ambiente: &#8220;Voc\u00ea n\u00e3o pode controlar as coisas se n\u00e3o as acompanhar&#8221;. Esse ditado mostra como \u00e9 importante observar atentamente o que fazemos. Isso nos ajuda a distinguir os esfor\u00e7os bem-sucedidos que fazem a diferen\u00e7a das a\u00e7\u00f5es que consomem recursos e podem n\u00e3o ser t\u00e3o \u00fateis.<\/p>\n\n\n\n<p>Apresentamos o programa <a href=\"https:\/\/cloud.google.com\/blog\/topics\/sustainability\/measuring-your-sustainability-initiative-for-success\">Google Cloud Ready<\/a> &#8211; Sustainability, desenvolvido para auxiliar as organiza\u00e7\u00f5es em sua jornada de sustentabilidade, com foco na medi\u00e7\u00e3o. Criada h\u00e1 um ano, essa iniciativa reuniu parceiros especializados para medir fatores cruciais como qualidade do ar, gases de efeito estufa, uso de energia e consumo de recursos. Essas parcerias oferecem \u00e0s organiza\u00e7\u00f5es percep\u00e7\u00f5es precisas sobre seu impacto ambiental.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A base do progresso: Entendendo onde voc\u00ea est\u00e1<\/strong><\/h2>\n\n\n\n<p>Para atingir metas ambiciosas, voc\u00ea precisa de um ponto de partida claro. <a href=\"https:\/\/www.pwc.com\/ph\/en\/publications\/ph-columns\/business-unusual\/2020\/what-esg-is-and-why-it-matters.html\">As normas ESG &#8211; normas<\/a>que regem as pr\u00e1ticas ambientais, sociais e de governan\u00e7a &#8211; est\u00e3o ganhando for\u00e7a progressivamente.<\/p>\n\n\n\n<p>Somente em 2021, foram introduzidas 225 pol\u00edticas novas ou aprimoradas. At\u00e9 2025, prev\u00ea-se que um surpreendente ter\u00e7o dos ativos globais gerenciados, totalizando US$ 53 trilh\u00f5es, esteja sob mandatos de ESG. Essa \u00eanfase crescente em resultados tang\u00edveis ressalta a necessidade de resultados verific\u00e1veis perante governos, \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o do setor, organiza\u00e7\u00f5es n\u00e3o governamentais (ONGs) e consumidores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mapeando o progresso invis\u00edvel: O desafio de medir o ESG<\/strong><\/h2>\n\n\n\n<p>Medir o progresso pode ser um desafio, especialmente quando se trata de programas ESG eficazes. Uma pesquisa recente da Harris, realizada para o Google Cloud, mostrou que apenas 22% das organiza\u00e7\u00f5es est\u00e3o medindo ativamente seus programas oficiais de ESG, o que representa 3% a menos do que no ano passado.<\/p>\n\n\n\n<p>A falta de ferramentas de medi\u00e7\u00e3o coloca os l\u00edderes em uma situa\u00e7\u00e3o complicada. Um grande n\u00famero de 87% dos entrevistados deseja melhores ferramentas para medir o andamento de seus esfor\u00e7os ambientais. Esse desejo vem da necessidade de estabelecer metas que possam ser alcan\u00e7adas e apoiadas por informa\u00e7\u00f5es reais.<\/p>\n\n\n\n<p>Muitos l\u00edderes admitem que, \u00e0s vezes, estabelecem metas para serem ecologicamente corretos, mas n\u00e3o t\u00eam maneiras claras de medir, melhorar e tornar essas metas reais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Capacitando o progresso: Apresentando o Google Cloud Ready &#8211; Sustainability<\/strong><\/h2>\n\n\n\n<p>Voc\u00ea pode conhecer o programa Google Cloud Ready &#8211; Sustainability. Essa iniciativa tem como objetivo ajudar as organiza\u00e7\u00f5es em v\u00e1rios est\u00e1gios de sua jornada de sustentabilidade, come\u00e7ando pela medi\u00e7\u00e3o. De fato, a medi\u00e7\u00e3o \u00e9 o alicerce desse programa.<\/p>\n\n\n\n<p>Lan\u00e7ado h\u00e1 um ano, o programa Google Cloud Ready &#8211; Sustainability reuniu um grupo de parceiros especializados em medir aspectos cr\u00edticos, como qualidade do ar, gases de efeito estufa, consumo de energia e utiliza\u00e7\u00e3o de recursos. Essas parcerias permitem que as organiza\u00e7\u00f5es obtenham insights precisos sobre sua pegada ambiental.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Parceiros em progresso: Pioneirismo em um futuro mais verde<\/strong><\/h3>\n\n\n\n<p><strong>1. Aclima: Respirando ar fresco em percep\u00e7\u00f5es ambientais<\/strong><\/p>\n\n\n\n<p>A Aclima emprega sensores para monitorar a qualidade do ar e rastrear o impacto da polui\u00e7\u00e3o no clima. Seus amplos esfor\u00e7os de coleta de dados abrangem os Estados Unidos e quase 20 pa\u00edses, esclarecendo milh\u00f5es de pessoas sobre a qualidade do ar.<\/p>\n\n\n\n<p><strong>2. BlueSky Resources: Limpando os c\u00e9us das preocupa\u00e7\u00f5es com emiss\u00f5es<\/strong><\/p>\n\n\n\n<p>A BlueSky Resources capacita os setores globais a quantificar e lidar com as emiss\u00f5es atmosf\u00e9ricas por meio de uma abordagem independente de sensores. Seu monitoramento abrange 180 locais em todo o mundo, oferecendo medi\u00e7\u00f5es verificadas e percep\u00e7\u00f5es sobre os setores de minera\u00e7\u00e3o, gest\u00e3o de res\u00edduos e energia.<\/p>\n\n\n\n<p><strong>3. Floodbase: Navegando no dil\u00favio de dados sobre enchentes<\/strong><\/p>\n\n\n\n<p>A Floodbase prev\u00ea e gerencia riscos de inunda\u00e7\u00e3o usando dados de sat\u00e9lite e algoritmos inteligentes. Essa solu\u00e7\u00e3o ajuda as comunidades a se prepararem para os desafios relacionados \u00e0s enchentes, especialmente em \u00e1reas de alto risco.<\/p>\n\n\n\n<p><strong>4. Floodlight: iluminando o impacto ambiental<\/strong><\/p>\n\n\n\n<p>O Floodlight agrega sensores terrestres, sat\u00e9lites e dados de IA para ajudar as empresas a avaliar sua pegada ambiental. Essa abordagem orientada por insights ajuda a tomar decis\u00f5es informadas para um futuro mais sustent\u00e1vel.<\/p>\n\n\n\n<p><strong>5. Keen AI: Pioneirismo em insights de energia orientados por IA<\/strong><\/p>\n\n\n\n<p>A tecnologia avan\u00e7ada de intelig\u00eancia artificial da Keen AI coleta, analisa e compartilha dados cr\u00edticos de infraestrutura de energia. Isso permite que as empresas avaliem as condi\u00e7\u00f5es do sistema de energia e prevejam estados futuros, otimizando os esfor\u00e7os de sustentabilidade.<\/p>\n\n\n\n<p><strong>6. Planeta: Visualizando a Terra por meio de uma lente de sat\u00e9lite<\/strong><\/p>\n\n\n\n<p>Por meio de imagens de sat\u00e9lite, o Planet permite o monitoramento em tempo real das mudan\u00e7as ambientais. Esses dados permitem que pesquisadores e organiza\u00e7\u00f5es respondam proativamente aos desafios ambientais em evolu\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>7. Sust Global: Navegando pelo risco clim\u00e1tico com dados perspicazes<\/strong><\/p>\n\n\n\n<p>Os produtos de dados de risco clim\u00e1tico da Sust Global ajudam as empresas a avaliar os riscos de desastres relacionados ao clima. Isso ajuda a desenvolver estrat\u00e9gias de mitiga\u00e7\u00e3o de riscos e diversifica\u00e7\u00e3o de portf\u00f3lio.<\/p>\n\n\n\n<p><strong>8. UP42: Scaling Solutions with Satellite Data (Solu\u00e7\u00f5es em escala com dados de sat\u00e9lite<\/strong> ) A UP42 fornece acesso f\u00e1cil a dados de sat\u00e9lite, permitindo o desenvolvimento de solu\u00e7\u00f5es para desafios como reflorestamento e preven\u00e7\u00e3o de desastres.<\/p>\n\n\n\n<p><strong>9. Watershed: Capacitando escolhas respons\u00e1veis pelo clima<\/strong><\/p>\n\n\n\n<p>A plataforma clim\u00e1tica corporativa da Watershed permite que as empresas me\u00e7am, relatem e reduzam sua pegada de carbono com efici\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Medi\u00e7\u00e3o para o progresso: Um caminho para a responsabilidade<\/strong><\/h3>\n\n\n\n<p>A medi\u00e7\u00e3o eficaz \u00e9 semelhante a tra\u00e7ar um curso antes de embarcar em uma jornada. Uma compreens\u00e3o clara do ponto de partida \u00e9 essencial para tra\u00e7ar uma trajet\u00f3ria de sucesso.<\/p>\n\n\n\n<p>Notavelmente, essa medi\u00e7\u00e3o n\u00e3o se refere apenas a beneficiar o planeta, mas tamb\u00e9m a cultivar a confian\u00e7a dos clientes, das comunidades e dos \u00f3rg\u00e3os reguladores. Informa\u00e7\u00f5es precisas e transparentes promovem decis\u00f5es informadas para as partes interessadas e os l\u00edderes empresariais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Impulsionando mudan\u00e7as sustent\u00e1veis: A vis\u00e3o do Google Cloud Ready &#8211; Sustainability<\/strong><\/h3>\n\n\n\n<p>O programa Google Cloud Ready &#8211; Sustainability \u00e9 uma prova do poder da tecnologia em facilitar mudan\u00e7as positivas. Com uma rede de parceiros em expans\u00e3o, essa iniciativa equipa as organiza\u00e7\u00f5es com as ferramentas necess\u00e1rias para medir, relatar e aprimorar seu impacto ambiental.<\/p>\n\n\n\n<p>Para explorar esses parceiros e suas ofertas, <a href=\"https:\/\/googlecloud.folloze.com\/sustainability\">visite a plataforma<\/a> e o marketplace <a href=\"https:\/\/googlecloud.folloze.com\/sustainability\">do Google Cloud<\/a>. A uni\u00e3o de for\u00e7as pode abrir o caminho para um mundo mais saud\u00e1vel e seguro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p>O &#8220;Google Cloud Ready &#8211; Sustainability&#8221; auxilia os esfor\u00e7os ecol\u00f3gicos por meio de parcerias de medi\u00e7\u00e3o precisas, catalisando mudan\u00e7as positivas na jornada da sustentabilidade.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":1502,"featured_media":26728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3095],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"O &quot;Google Cloud Ready - Sustainability&quot; auxilia os esfor\u00e7os ecol\u00f3gicos por meio de parcerias de medi\u00e7\u00e3o precisas, catalisando mudan\u00e7as positivas na jornada da sustentabilidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-24T19:53:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T16:57:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Raf Chomsky\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raf Chomsky\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\"},\"author\":{\"name\":\"Raf Chomsky\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339\"},\"headline\":\"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade\",\"datePublished\":\"2023-08-24T19:53:01+00:00\",\"dateModified\":\"2024-08-10T16:57:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\"},\"wordCount\":1120,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\",\"name\":\"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png\",\"datePublished\":\"2023-08-24T19:53:01+00:00\",\"dateModified\":\"2024-08-10T16:57:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png\",\"width\":1600,\"height\":667,\"caption\":\"Google cloud logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339\",\"name\":\"Raf Chomsky\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632\",\"caption\":\"Raf Chomsky\"},\"description\":\"Dedicated author deeply engaged in sustainability issues. My writing focuses on practical, impactful solutions and communicates the urgency of environmental responsibility. With a commitment to raising awareness, I aim to inform and inspire readers to embrace sustainable practices in their daily lives.\",\"sameAs\":[\"https:\/\/sustainablereview.com\/\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/nonagency\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review","og_description":"O \"Google Cloud Ready - Sustainability\" auxilia os esfor\u00e7os ecol\u00f3gicos por meio de parcerias de medi\u00e7\u00e3o precisas, catalisando mudan\u00e7as positivas na jornada da sustentabilidade.","og_url":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/","og_site_name":"Sustainable Review","article_published_time":"2023-08-24T19:53:01+00:00","article_modified_time":"2024-08-10T16:57:43+00:00","og_image":[{"width":1600,"height":667,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png","type":"image\/png"}],"author":"Raf Chomsky","twitter_card":"summary_large_image","twitter_creator":"@sustainreview","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Raf Chomsky","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/"},"author":{"name":"Raf Chomsky","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339"},"headline":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade","datePublished":"2023-08-24T19:53:01+00:00","dateModified":"2024-08-10T16:57:43+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/"},"wordCount":1120,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/","url":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/","name":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png","datePublished":"2023-08-24T19:53:01+00:00","dateModified":"2024-08-10T16:57:43+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2023\/08\/GCP.png","width":1600,"height":667,"caption":"Google cloud logo"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/google-cloud-prepara-nova-abordagem-para-medir-o-impacto-ambiental-e-atingir-metas-de-sustentabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Google Cloud Ready: Nova abordagem para medir o impacto ambiental e atingir as metas de sustentabilidade"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/85320f9ca6ed105ac24fd5721a2ce339","name":"Raf Chomsky","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/ad8c67d6aa8afe7c0a7adebd55367f9e.jpg?ver=1778640632","caption":"Raf Chomsky"},"description":"Dedicated author deeply engaged in sustainability issues. My writing focuses on practical, impactful solutions and communicates the urgency of environmental responsibility. With a commitment to raising awareness, I aim to inform and inspire readers to embrace sustainable practices in their daily lives.","sameAs":["https:\/\/sustainablereview.com\/"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/nonagency\/"}]}},"wpml_translations":{"en":"26727","pl":"60497","pt-br":"39192"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39192"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/1502"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39192"}],"version-history":[{"count":1,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39192\/revisions"}],"predecessor-version":[{"id":39704,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39192\/revisions\/39704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/26728"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}