{"id":39367,"date":"2022-07-28T09:00:00","date_gmt":"2022-07-28T13:00:00","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39367"},"modified":"2024-08-10T13:05:51","modified_gmt":"2024-08-10T17:05:51","slug":"isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/","title":{"rendered":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas"},"content":{"rendered":"\n<p>Tive a sorte de conversar com o CEO da Upstream, Matt Prindiville. Durante nossa conversa, falamos sobre sustentabilidade versus mudan\u00e7a clim\u00e1tica, o poder dos setores p\u00fablico e privado, ESG, economias circulares, otimismo clim\u00e1tico racional e muito mais!<\/p>\n\n\n\n<p><a href=\"http:\/\/upstreamsolutions.org\" target=\"_blank\" rel=\"noreferrer noopener\">A Upstream Solutions<\/a> \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos fundada em 2003 com a miss\u00e3o de n\u00e3o apenas reduzir, mas tamb\u00e9m remover o pl\u00e1stico de uso \u00fanico do mundo. Sua organiza\u00e7\u00e3o encontra, fabrica e celebra solu\u00e7\u00f5es pr\u00e1ticas que ajudam pessoas, empresas e comunidades a mudar do uso \u00fanico para a reutiliza\u00e7\u00e3o. Nas \u00faltimas d\u00e9cadas, eles trabalharam com in\u00fameras organiza\u00e7\u00f5es comprometidas com um futuro mais sustent\u00e1vel.<\/p>\n\n\n\n<p>Quando perguntado sobre as implica\u00e7\u00f5es futuras das mudan\u00e7as clim\u00e1ticas, Prindiville disse: &#8220;Sou um otimista. O que os cientistas est\u00e3o dizendo \u00e9, obviamente, muito assustador. Mas quando penso nas mudan\u00e7as que vi em minha carreira, \u00e9 incr\u00edvel o quanto j\u00e1 avan\u00e7amos. Daqui a dez anos, voc\u00ea ver\u00e1 que a responsabilidade ambiental e social ser\u00e1 a norma em todo o mundo.&#8221;<\/p>\n\n\n\n<p><strong>Aprofunde-se \u2192 10 min<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta (JW): Acho que muitas pessoas est\u00e3o interessadas em aprender como trabalhar em tempo integral no setor clim\u00e1tico. Conte-nos sobre sua jornada.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Como voc\u00ea fez a transi\u00e7\u00e3o da pol\u00edtica p\u00fablica para se tornar l\u00edder em uma grande organiza\u00e7\u00e3o sem fins lucrativos?<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">O colapso do Georges Bank<\/h4>\n\n\n\n<p><strong>Resposta (MP)<\/strong>: N\u00e3o sei at\u00e9 onde voc\u00ea quer ir. Cresci em Massachusetts, em uma pequena cidade pesqueira chamada Gloucester, e meus pais n\u00e3o eram ambientalistas. Portanto, o ativismo ambiental n\u00e3o fazia parte da minha educa\u00e7\u00e3o. Uma coisa de que me lembro \u00e9 que muitos dos pais de meus amigos eram pescadores. Portanto, est\u00e1vamos cercados por fam\u00edlias de pescadores.<\/p>\n\n\n\n<p>Lembro-me de quando a pesca do bacalhau entrou em colapso em <a href=\"https:\/\/www.encyclopedia.com\/environment\/encyclopedias-almanacs-transcripts-and-maps\/georges-bank-collapse-ground-fishery\" target=\"_blank\" rel=\"noreferrer noopener\">Georges Bank<\/a> no in\u00edcio da d\u00e9cada de 1990. Com muitas fam\u00edlias dependentes do neg\u00f3cio da pesca, nossa cidade foi economicamente destru\u00edda da noite para o dia. As casas foram executadas e os carros foram retomados. Foi um grande problema.<\/p>\n\n\n\n<p>Percebi que, se n\u00e3o cuidarmos do mundo natural, isso n\u00e3o ser\u00e1 ruim apenas para a vida selvagem e o planeta. A mudan\u00e7a clim\u00e1tica tamb\u00e9m pode ter ramifica\u00e7\u00f5es significativas sobre as pessoas e as comunidades. E acho que isso ficou comigo desde ent\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ativismo ambiental no campus na d\u00e9cada de 1990<\/h4>\n\n\n\n<p>Mais uma vez, eu n\u00e3o estava pensando em fazer qualquer tipo de carreira na \u00e1rea ambiental. Acho que estava pensando em um caminho mais comum, como ser m\u00e9dico ou fazer um MBA.<\/p>\n\n\n\n<p>Na faculdade, tive uma aula de semin\u00e1rio no primeiro ano que mudou meu caminho. Lemos o livro <a href=\"https:\/\/amzn.to\/3zoP6fl\" target=\"_blank\" rel=\"noreferrer noopener\">Ecology of Commerce (Ecologia do Com\u00e9rcio<\/a> ) de um cara chamado Paul Hawken. Ele continua escrevendo e publicando at\u00e9 hoje. Ele \u00e9 um ser humano maravilhoso e um excelente ambientalista seminal.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=k1wXHx2DsSU<\/div><\/figure>\n\n\n\n<p>Esse livro foi a primeira vez que tive contato com a ideia do que hoje chamamos de economia circular. N\u00e3o us\u00e1vamos essa terminologia ou linguagem na \u00e9poca, mas ele enfatizou sentimentos semelhantes em seu livro. Ele a descreveu como &#8220;Capitalismo Natural&#8221;.<\/p>\n\n\n\n<p>Cerca de cinco ou seis anos depois, <a href=\"https:\/\/mcdonough.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bill McDonough<\/a> lan\u00e7ou seu <a href=\"https:\/\/amzn.to\/3vhaQHu\" target=\"_blank\" rel=\"noreferrer noopener\">livro Cradle to Cradle<\/a>. Esse foi outro livro essencial em minha educa\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p>Quando eu estava na escola, as pessoas que me cercavam eram ambientalistas radicais. Tive a oportunidade de conviver com esses jovens entusiasmados, vendo a paix\u00e3o deles. E isso causou um impacto profundo. Muitos eram volunt\u00e1rios em organiza\u00e7\u00f5es ambientais locais e se juntaram ao <a href=\"https:\/\/ospirgstudents.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oregon Student Public Interest Research Group<\/a>, ou SPIRG.<\/p>\n\n\n\n<p>Eles estavam tentando fazer com que eu os ajudasse a reunir assinaturas, espalhar a boa not\u00edcia e assim por diante. Pouco tempo depois, abandonei a escola e passei a frequentar parques nacionais e \u00e1reas de esqui. Eu simplesmente me apaixonei pelo Oeste e comecei a me expor a muitas das lutas pela conserva\u00e7\u00e3o que estavam acontecendo l\u00e1.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Voltei para o Maine para lutar em n\u00edvel de base.<\/h4>\n\n\n\n<p>Por fim, mudei-me para o Maine, onde meus pais haviam se estabelecido, e terminei a faculdade aqui no Maine. Minha ideia inicial era decidir, naquele momento, que eu queria seguir uma carreira em pol\u00edtica ambiental. Inicialmente, eu queria tentar ci\u00eancia normal ou estudos ecol\u00f3gicos, mas senti que voc\u00ea poderia fazer a maior quantidade de mudan\u00e7as no trabalho de pol\u00edtica.<\/p>\n\n\n\n<p>Passei dez anos trabalhando em um grupo de vigil\u00e2ncia ambiental no Maine, uma grande organiza\u00e7\u00e3o com 30 funcion\u00e1rios e um or\u00e7amento de US$ 3 a 4 milh\u00f5es. Era um tipo de empresa de lobby ambiental poderosa no Maine. Passei de <a href=\"https:\/\/sustainablereview.com\/voting-matters-climate-change\/\" target=\"_blank\" rel=\"noreferrer noopener\">organizador de base<\/a> a diretor legislativo. Quando sa\u00ed, estava dirigindo o lobby da c\u00e2mara estadual.<\/p>\n\n\n\n<p>No meu primeiro dia de trabalho, fui encarregado de organizar uma coletiva de imprensa para uma lei ambiental que foi a primeira do g\u00eanero no pa\u00eds. A quest\u00e3o era a obten\u00e7\u00e3o de um projeto de lei que exigia que os fabricantes de computadores e televisores pagassem pela <a href=\"https:\/\/sustainablereview.com\/pt-br\/reciclagem-de-eletronicos\/\">coleta e reciclagem de seus produtos<\/a>. Isso \u00e9 chamado de <a href=\"https:\/\/www.rila.org\/blog\/2021\/04\/extended-producer-responsibility-bills#:~:text=EPR%20in%20the%20U.S.&amp;text=These%20laws%20require%20paint%20companies,when%20they%20purchase%20new%20paint.\" target=\"_blank\" rel=\"noreferrer noopener\">responsabilidade estendida do produtor.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=86lLauhTikU<\/div><\/figure>\n\n\n\n<p>Eu havia lido sobre isso na escola e, em meu primeiro dia de trabalho, comecei a trabalhar nisso. Essa lei de EPR abriu caminho para que o resto do pa\u00eds a seguisse.<\/p>\n\n\n\n<p>H\u00e1 vinte anos, havia muito poucos especialistas nessa \u00e1rea nos Estados Unidos, e um deles era o fundador da Upstream.<\/p>\n\n\n\n<p>Estabeleci um relacionamento com o fundador da <a href=\"http:\/\/upstreamsolutions.org\" target=\"_blank\" rel=\"noreferrer noopener\">Upstream<\/a> na d\u00e9cada de 1990, levando-o ao Maine para ajudar a testemunhar e redigir o projeto de lei que acabou sendo aprovado. Posteriormente, trabalhamos juntos em v\u00e1rias outras leis federais in\u00e9ditas.<\/p>\n\n\n\n<p>Essas leis exigiam que n\u00e3o apenas os fabricantes de computadores e de TVs ampliassem sua responsabilidade como produtores, mas tamb\u00e9m as empresas de telefonia celular, os fabricantes de produtos contendo merc\u00fario e os fabricantes de tintas. Todos eles tiveram que come\u00e7ar a pagar pela <a href=\"https:\/\/sustainablereview.com\/recycling-electronics\/\" target=\"_blank\" rel=\"noreferrer noopener\">coleta e reciclagem segura<\/a> de seus <a href=\"https:\/\/sustainablereview.com\/recycling-electronics\/\" target=\"_blank\" rel=\"noreferrer noopener\">produtos<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Matt \u00e9 contratado pela Upstream.<\/h4>\n\n\n\n<p>Quando entrei para a Upstream, eu estava pronto para uma mudan\u00e7a. Fizemos uma mudan\u00e7a pol\u00edtica significativa em meu estado natal, o Maine. E vi que provavelmente jogaria na defesa nos pr\u00f3ximos quatro anos, depois de jogar no ataque por dez.<\/p>\n\n\n\n<p>Eu queria descobrir como usar as habilidades que havia desenvolvido e trabalhar no cen\u00e1rio nacional, n\u00e3o apenas em n\u00edvel estadual e durante o per\u00edodo em que trabalhei na organiza\u00e7\u00e3o anterior.<\/p>\n\n\n\n<p>Muitos dos meus trabalhos anteriores lidavam com campanhas e coaliz\u00f5es nacionais. Agora, na <a href=\"http:\/\/upstreamsolutions.org\">Upstream<\/a>, est\u00e1vamos fazendo pol\u00edticas em n\u00edvel estadual que lidavam com grupos ambientais de grande escala e outros grupos ambientais estaduais em todo o pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?time_continue=1&amp;v=t1JxxQVS_30<\/div><\/figure>\n\n\n\n<p>Minha carreira n\u00e3o se limitou a ajudar os produtos a se tornarem mais sustent\u00e1veis. Tamb\u00e9m influenciamos a pol\u00edtica de mudan\u00e7a clim\u00e1tica, regulamentando o uso de toxinas e implementando pol\u00edticas de sa\u00fade ambiental. Ajudamos a aprovar uma nova legisla\u00e7\u00e3o clim\u00e1tica no Congresso. Essa experi\u00eancia me ajudou a criar redes nacionais e a ver a m\u00e1gica das ONGs se unirem e alinharem sua arrecada\u00e7\u00e3o de fundos, recursos e trabalho de m\u00eddia. Somos muito mais poderosos quando trabalhamos juntos e n\u00e3o separados.<\/p>\n\n\n\n<p>Na Upstream, a organiza\u00e7\u00e3o se concentrava principalmente em ajudar os governos estaduais e locais a se organizarem em torno dessa \u00e1rea de pol\u00edtica de responsabilidade estendida do produtor. Eu queria trazer as ONGs como um componente significativo para aumentar o poder e a influ\u00eancia nas casas estaduais e no Congresso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta: Voc\u00ea falou muito sobre o impacto do seu trabalho. Vamos nos aprofundar nisso, diferenciando entre mudan\u00e7a clim\u00e1tica e sustentabilidade.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 mais importante para voc\u00ea? A reciclagem, a reutiliza\u00e7\u00e3o, a restaura\u00e7\u00e3o dos oceanos, a cria\u00e7\u00e3o de economias circulares de escala ou o cumprimento de metas mais amplas de mitiga\u00e7\u00e3o do clima, como o desmatamento e a descarboniza\u00e7\u00e3o?<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Que papel a Upstream desempenha na conversa mais ampla sobre mudan\u00e7as clim\u00e1ticas?<\/h3>\n\n\n\n<p><strong>Resposta (MP)<\/strong><strong>: <\/strong>Adoro essa pergunta! Quero dizer, grande parte da mudan\u00e7a clim\u00e1tica \u00e9 impulsionada pelo consumo. Gostamos de pensar que n\u00e3o se trata tanto de consumo, porque tudo precisa ser consumido para viver, mas o consumo excessivo e desnecess\u00e1rio est\u00e1 impulsionando o consumo excessivo e desnecess\u00e1rio do planeta, certo?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Economias lineares versus economias circulares<\/h4>\n\n\n\n<p>Suponha que voc\u00ea observe a economia linear como ela existe hoje. As empresas de extra\u00e7\u00e3o extraem metais, perfuram para obter g\u00e1s, derrubam florestas e criam todos os materiais que se transformam nas coisas que compramos.<\/p>\n\n\n\n<p>Em seguida, voc\u00ea tem as marcas que tornam os materiais utiliz\u00e1veis e os embalam. Em seguida, os varejistas ajudam a vend\u00ea-los. Por fim, quando os consumidores terminam de usar um produto, temos toda essa outra cadeia de gerenciamento de res\u00edduos.<\/p>\n\n\n\n<p>Essa estrutura econ\u00f4mica atual favorece a extra\u00e7\u00e3o. Temos fornecedores e produtores na linha de frente e empresas de gerenciamento de res\u00edduos na linha de tr\u00e1s. Assim, uma parte consider\u00e1vel das emiss\u00f5es de mudan\u00e7as clim\u00e1ticas nos Estados Unidos (cerca de 55%) \u00e9 proveniente da fabrica\u00e7\u00e3o, do uso e do descarte de materiais.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">O uso e o descarte de materiais<\/h4>\n\n\n\n<p>Muitas pessoas pensam na mudan\u00e7a clim\u00e1tica no contexto dos carros, do aquecimento da casa, do fornecimento de energia para o pr\u00e9dio do escrit\u00f3rio e do acendimento das luzes. Mas muito do que impulsiona a mudan\u00e7a clim\u00e1tica e a polui\u00e7\u00e3o \u00e9 o consumo, e uma grande parte dele \u00e9 desnecess\u00e1ria, o que chamamos de consumo excessivo desnecess\u00e1rio.<\/p>\n\n\n\n<p>Em vez de <a href=\"https:\/\/sustainablereview.com\/better-brands-is-starbucks-sustainable\/\" target=\"_blank\" rel=\"noreferrer noopener\">a Starbucks desenvolver um sistema de copos reemb<\/a>ols\u00e1veis, \u00e9 necess\u00e1rio ter um copo reutiliz\u00e1vel e um sistema de compartilhamento ou aluguel de copos para que esses copos reutiliz\u00e1veis sejam coletados e lavados. Voc\u00ea faz um copo e o usa centenas de vezes.<\/p>\n\n\n\n<p>Em vez disso, voc\u00ea est\u00e1 servindo ao mesmo cliente centenas e centenas de copos descart\u00e1veis.<\/p>\n\n\n\n<p>Voc\u00ea soma isso ao longo do tempo, e qual \u00e9 a pegada de carbono desse copo descart\u00e1vel em compara\u00e7\u00e3o com um copo reutiliz\u00e1vel? Al\u00e9m disso, n\u00e3o apenas a pegada de carbono. Qual \u00e9 a pegada de recursos naturais tamb\u00e9m? Quantas \u00e1rvores voc\u00ea sente para sustentar o h\u00e1bito de tomar caf\u00e9? Voc\u00ea acha que \u00e9 poss\u00edvel fazer esse copo reutiliz\u00e1vel uma \u00fanica vez e mant\u00ea-lo por tanto tempo quanto poss\u00edvel?<\/p>\n\n\n\n<p>Mas as solu\u00e7\u00f5es circulares nem sempre s\u00e3o simples. Digamos que a x\u00edcara fique muito danificada ou arranhada. Ele ainda est\u00e1 em um sistema de ciclo fechado? Ele \u00e9 reciclado para a pr\u00f3xima x\u00edcara?<\/p>\n\n\n\n<p>\u00c9 essa circularidade que precisamos criar, n\u00e3o apenas para o consumo de caf\u00e9, a fim de reduzir os <a href=\"https:\/\/sustainablereview.com\/environmental-impact-of-takeout-food\/\" target=\"_blank\" rel=\"noreferrer noopener\">impactos ambientais desse<\/a> consumo, mas para todos os produtos consum\u00edveis. E o que gosto de dizer \u00e0s pessoas \u00e9 que n\u00e3o levem apenas o caf\u00e9 para casa.<\/p>\n\n\n\n<p>\u00c9 isso que \u00e9 frustrante. A maioria dos produtores pode utilizar sistemas e servi\u00e7os reutiliz\u00e1veis. Precisamos reduzir essas enormes cadeias de suprimentos de embalagens de uso \u00fanico, que s\u00e3o a norma para todos os produtos de consumo. \u00c9 a norma. Seja em <a href=\"https:\/\/sustainablereview.com\/environmental-impact-of-takeout-food\/\" target=\"_blank\" rel=\"noreferrer noopener\">comida para viagem<\/a>, caf\u00e9 para viagem, no supermercado, nas bebidas que voc\u00ea compra na loja de conveni\u00eancia e assim por diante.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fazendo com que os produtores reutilizem<\/h4>\n\n\n\n<p>O mundo est\u00e1 se transformando cada vez mais em fluxos de servi\u00e7os de reutiliza\u00e7\u00e3o. N\u00e3o estamos falando de o cliente trazer seus motivos razo\u00e1veis para onde quer que voc\u00ea v\u00e1, ou suas coisas boas para qualquer lugar.<\/p>\n\n\n\n<p>As empresas est\u00e3o criando sistemas que permitem que a reutiliza\u00e7\u00e3o seja a forma padr\u00e3o de consumo. Agora estamos familiarizados com a forma como vamos ao supermercado ou fazemos pedidos on-line.<\/p>\n\n\n\n<p>Voc\u00ea recebe o produto, n\u00f3s o levamos para casa ou ele chega em nossa casa. E voc\u00ea tem uma variedade de lixeiras onde colocamos as coisas, como uma lixeira, uma lixeira de reciclagem, talvez voc\u00ea tenha uma lixeira de compostagem. Como voc\u00ea pode adaptar essa infraestrutura?<\/p>\n\n\n\n<p>Os padr\u00f5es de conveni\u00eancia ainda est\u00e3o l\u00e1. Voc\u00ea n\u00e3o precisa de lixeiras de reutiliza\u00e7\u00e3o extras em todos os lugares, al\u00e9m das outras lixeiras. Tamb\u00e9m podemos adaptar a lixeira de reciclagem para colocar recipientes utiliz\u00e1veis nela. A UPS e a FedEx poderiam vir at\u00e9 nossa casa ou pr\u00e9dio de apartamentos algumas vezes por semana.<\/p>\n\n\n\n<p>E se houvesse um leiteiro e ele tamb\u00e9m pegasse recipientes reutiliz\u00e1veis enquanto os deixasse?<\/p>\n\n\n\n<p>E quando voc\u00ea est\u00e1 fora de casa e em tr\u00e2nsito em uma cidade onde n\u00e3o h\u00e1 apenas uma lixeira ou uma lixeira, mas agora voc\u00ea tem quiosques para colocar o caf\u00e9 reutiliz\u00e1vel que acabou de pegar emprestado na cafeteria ou um recipiente para viagem que acabou de levar para o almo\u00e7o do dia?<\/p>\n\n\n\n<p>Veja, se a infraestrutura e os padr\u00f5es de conveni\u00eancia estiverem presentes, os consumidores ainda estar\u00e3o recebendo o que desejam e precisam. Ainda assim, isso gera menos desperd\u00edcio, e o \u00f4nus de mudar a forma como consumimos agora recai sobre as empresas, e n\u00e3o sobre o indiv\u00edduo.<\/p>\n\n\n\n<p>Portanto, esse \u00e9 o mundo que estamos trabalhando para criar. E eu diria que a excelente not\u00edcia \u00e9 que temos GRANDES marcas, n\u00e3o apenas pequenas empresas e cidades, que querem fazer isso.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">As marcas querem descobrir isso. Porque elas sabem de duas coisas:<\/h5>\n\n\n\n<p>1) se quiserem reduzir suas contribui\u00e7\u00f5es para a mudan\u00e7a clim\u00e1tica, mais reciclagem n\u00e3o ser\u00e1 suficiente. Elas precisam encontrar maneiras de reduzir as embalagens e reduzir o n\u00famero de recursos para vender seus produtos, pois a reutiliza\u00e7\u00e3o deve fazer parte disso.<\/p>\n\n\n\n<p>2) em escala, a embalagem real \u00e9 mais barata do que a venda. Sentimos que n\u00e3o estamos apenas vendendo algo melhor para o meio ambiente. A escala \u00e9 melhor para os neg\u00f3cios e para a experi\u00eancia do consumidor. At\u00e9 mesmo a est\u00e9tica de consumir produtos dur\u00e1veis e reutiliz\u00e1veis \u00e9 melhor do que beber em uma garrafa de pl\u00e1stico.<\/p>\n\n\n\n<p>Voc\u00ea prefere tomar seu caf\u00e9 em uma caneca de cer\u00e2mica reutiliz\u00e1vel ou em um copo de a\u00e7o inoxid\u00e1vel, ou prefere tom\u00e1-lo em um copo de papel ou em um copo de pl\u00e1stico barato com um furo no canudo? Voc\u00ea prefere? \u00c9 uma experi\u00eancia melhor, al\u00e9m de ser melhor para o meio ambiente e em escala.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta: Onde voc\u00ea acha que pode fazer a diferen\u00e7a mais significativa entre empresas, governo ou organiza\u00e7\u00f5es sem fins lucrativos?<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Devemos nos concentrar principalmente em consertar o setor privado? H\u00e1 uma fun\u00e7\u00e3o clara que os governos locais ou nacionais devem desempenhar al\u00e9m do trabalho sem fins lucrativos que voc\u00ea realiza?<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Como voc\u00ea v\u00ea a contribui\u00e7\u00e3o de todos os diferentes atores?<\/h3>\n\n\n\n<p><strong>Resposta (MP)<\/strong><strong>: <\/strong>Voc\u00ea n\u00e3o pode ter empresas individuais tentando se consertar sozinhas. Imagine que cada empresa tivesse que descobrir como reciclar seus produtos sem nenhum apoio do governo. \u00c9 a mesma coisa com a reutiliza\u00e7\u00e3o.<\/p>\n\n\n\n<p>Precisamos de parcerias p\u00fablico-privadas significativas entre o governo e as grandes marcas. Os provedores de servi\u00e7os tamb\u00e9m precisam desenvolver uma infraestrutura que possa atender a v\u00e1rias empresas ao mesmo tempo em uma plataforma semelhante.<\/p>\n\n\n\n<p>No momento, voc\u00ea pode ir \u00e0 \u00e1rea industrial de qualquer pa\u00eds. Normalmente, voc\u00ea ver\u00e1 um hub de log\u00edstica da Amazon, uma UPS ou uma instala\u00e7\u00e3o em nossa se\u00e7\u00e3o &#8220;Smurf&#8221; (como a chamamos na empresa), e essas instala\u00e7\u00f5es t\u00eam permiss\u00e3o para receber e retirar toneladas de caminh\u00f5es.<\/p>\n\n\n\n<p>Os servi\u00e7os ferrovi\u00e1rios ou portu\u00e1rios est\u00e3o entrando e saindo dessas \u00e1reas onde o mecanismo de distribui\u00e7\u00e3o est\u00e1 localizado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Voc\u00ea pode levar a reciclagem \u00e0 raiz do problema.<\/h4>\n\n\n\n<p>Agora imagine esse centro de distribui\u00e7\u00e3o bem ao lado da <a href=\"https:\/\/sustainablereview.com\/pt-br\/reciclagem-de-eletronicos\/\">instala\u00e7\u00e3o de reciclagem<\/a>. Atualmente, voc\u00ea tem uma lavadora que chega e aceita recipientes para viagem, garrafas para viagem para todos os clientes, recipientes para as embalagens cheias no supermercado ou produtos de higiene pessoal, embalagens de salgadinhos etc.<\/p>\n\n\n\n<p>Tudo isso chega a um ou v\u00e1rios parques industriais. Portanto, esses cont\u00eaineres chegam sujos. Eles s\u00e3o limpos, higienizados e secos. E ent\u00e3o, eles passam para a pr\u00f3xima fase, de reabastecimento e reabastecimento. Ent\u00e3o, isso \u00e9 o que usamos para consumir.<\/p>\n\n\n\n<p>O manuseio de produtos \u00e9 um grande neg\u00f3cio. Com rela\u00e7\u00e3o ao setor de bebidas, estive ao telefone com a Anheuser Busch na semana passada. 34% de seu produto em todo o mundo \u00e9 vendido em garrafas de vidro recarreg\u00e1veis &#8211; a maior empresa de cerveja do mundo. Um ter\u00e7o de seu produto \u00e9 em refil.<\/p>\n\n\n\n<p>Se voc\u00ea sabe como fazer isso, \u00e9 poss\u00edvel, e a infraestrutura n\u00e3o \u00e9 uma ci\u00eancia de foguetes. Voc\u00ea est\u00e1 certo? Na verdade, trata-se de reunir um n\u00famero suficiente de pessoas para se juntarem e criarem uma infraestrutura que possa atender a todas essas empresas ao mesmo tempo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta: A colabora\u00e7\u00e3o pode ser uma ferramenta poderosa para que voc\u00ea cumpra miss\u00f5es desafiadoras.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Voc\u00ea acha que as organiza\u00e7\u00f5es sem fins lucrativos existentes precisam de mais colabora\u00e7\u00e3o ou o mundo precisa de mais Upstreams?<\/h3>\n\n\n\n<p><strong>Resposta (MP)<\/strong>: A \u00fanica maneira de causar o maior impacto poss\u00edvel \u00e9 por meio da colabora\u00e7\u00e3o e do trabalho em rede. N\u00f3s existimos hoje gra\u00e7as \u00e0 nossa rede. Essas s\u00e3o as pessoas que atendemos, e se mais organiza\u00e7\u00f5es ambientais sem fins lucrativos estivessem procurando pessoas para se envolverem no crescimento e na constru\u00e7\u00e3o de nossa miss\u00e3o, isso seria bom. E isso pode acontecer em diferentes n\u00edveis, certo? Portanto, precisamos de mais organiza\u00e7\u00f5es sem fins lucrativos.<\/p>\n\n\n\n<p>Mais importante do que o n\u00famero de organiza\u00e7\u00f5es sem fins lucrativos, precisamos que as marcas existentes e os l\u00edderes governamentais fa\u00e7am uma mudan\u00e7a r\u00e1pida. N\u00e3o \u00e9 preciso que sejam os diretores de sustentabilidade que influenciem uma grande empresa, e os ativistas comunit\u00e1rios tamb\u00e9m podem mudar a sociedade.<\/p>\n\n\n\n<p>Para responder brevemente \u00e0 sua pergunta. Sou 100% a favor da colabora\u00e7\u00e3o, e tudo se resume \u00e0 mobiliza\u00e7\u00e3o de redes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta:<strong> <\/strong>Todos n\u00f3s estamos trabalhando nessa grande miss\u00e3o de ajudar o meio ambiente.<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ent\u00e3o, por que estamos fazendo isso? Devemos acreditar nisso se estamos construindo. Qual \u00e9 a perspectiva de longo prazo que voc\u00ea tem sobre o planeta?<\/h3>\n\n\n\n<p><strong>Resposta (MP)<\/strong>: Adoro essa pergunta. Sou um otimista.<\/p>\n\n\n\n<p>O que os cientistas est\u00e3o dizendo \u00e9, obviamente, muito assustador. Mas quando penso nas mudan\u00e7as que vi em minha carreira, \u00e9 incr\u00edvel o quanto avan\u00e7amos. H\u00e1 20 anos, n\u00e3o havia departamentos de sustentabilidade nas empresas nem departamentos de sustentabilidade nas cidades. Os estudos ambientais eram um nicho total de especializa\u00e7\u00e3o em universidades aleat\u00f3rias. Era um curso in\u00e9dito em algumas faculdades pequenas e aleat\u00f3rias.<\/p>\n\n\n\n<p>Hoje, as grandes empresas n\u00e3o podem funcionar sem algum tipo de compromisso com a sustentabilidade. O fato de voc\u00ea perceber ou n\u00e3o sua responsabilidade depende de uma lideran\u00e7a eficaz. Mas a mudan\u00e7a est\u00e1 acontecendo. Tamb\u00e9m vejo a pr\u00f3xima gera\u00e7\u00e3o surgindo, e as pessoas est\u00e3o famintas. Temos uma quantidade incr\u00edvel de tecnologia e m\u00eddia social como forma de disseminar ideias e conectar pessoas.<\/p>\n\n\n\n<p>Mesmo considerando apenas uma cadeia de suprimentos mais sustent\u00e1vel e resiliente, as informa\u00e7\u00f5es na ponta dos dedos das empresas e dos governos municipais est\u00e3o em um n\u00edvel completamente diferente do que quando comecei minha carreira.<\/p>\n\n\n\n<p>H\u00e1 vinte anos, as empresas eram 100% contr\u00e1rias a uma pol\u00edtica ambiental, o que era um trabalho \u00e1rduo para as organiza\u00e7\u00f5es sem fins lucrativos. No in\u00edcio da minha carreira, era uma mentalidade de soma zero, em que o vencedor leva tudo, n\u00f3s contra eles.<\/p>\n\n\n\n<p>Agora, voc\u00ea v\u00ea muitas empresas que consideram necess\u00e1ria a coopera\u00e7\u00e3o com as diretrizes ambientais. E acho que \u00e9 por isso que tenho esperan\u00e7a no futuro. Daqui a dez anos, voc\u00ea ver\u00e1 que <a href=\"https:\/\/sustainablereview.com\/do-csr-sustainability-programs-work\/\" target=\"_blank\" rel=\"noreferrer noopener\">a responsabilidade ambiental e social<\/a> ser\u00e1 a norma em todo o mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pergunta: Qual \u00e9 a posi\u00e7\u00e3o que voc\u00ea tem sobre ESG? Voc\u00ea acha que \u00e9 importante? Voc\u00ea acha que \u00e9 \u00fatil ou exagerado?<\/h3>\n\n\n\n<p><strong>Resposta (MP)<\/strong>: \u00d3tima pergunta. Acho que <a href=\"https:\/\/sustainablereview.com\/pt-br\/o-problema-com-os-fundos-esg-e-como-corrigi-los\/\">o ESG<\/a>, mais do que qualquer outra coisa, amplia a conversa sobre mudan\u00e7a clim\u00e1tica nos c\u00edrculos corporativos.<\/p>\n\n\n\n<p>Portanto, se voc\u00ea olhar para o <a href=\"https:\/\/sustainablereview.com\/the-problem-with-esg-funds-and-how-to-fix-them\/\" target=\"_blank\" rel=\"noreferrer noopener\">ESG hoje<\/a>, eu diria que a coisa mais significativa que ele realizou \u00e9 que um conjunto de corpora\u00e7\u00f5es em todo o mundo est\u00e1 lidando com a sustentabilidade de uma forma que n\u00e3o fazia antes.<\/p>\n\n\n\n<p>Ouvi todas as partes interessadas de qualquer tipo e ouvi todos os tipos de organiza\u00e7\u00e3o em todo o espectro pol\u00edtico. Voc\u00ea precisa perceber que se trata de um ato de equil\u00edbrio de diferentes desejos. \u00c9 assim que progredimos. \u00c9 assim que vamos mais longe, mais r\u00e1pido.<\/p>\n\n\n\n<p>Quando come\u00e7amos a apontar o dedo e a acrescentar culpa, come\u00e7amos a fracassar. Precisamos avan\u00e7ar como um grupo para enfrentar esses desafios incrivelmente complexos.<\/p>\n\n\n\n<p><em>Se voc\u00ea gostou desta entrevista, confira nossas outras entrevistas individuais com l\u00edderes em sustentabilidade, como <a href=\"https:\/\/sustainablereview.com\/1-on-1-brian-powers-temperpack\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brian Powers<\/a>, <a href=\"https:\/\/sustainablereview.com\/1-on-1-brian-powers-temperpack\/\" target=\"_blank\" rel=\"noreferrer noopener\">da TemperPack<\/a>, <a href=\"https:\/\/sustainablereview.com\/one-tree-planted-matt-hill\/\" target=\"_blank\" rel=\"noreferrer noopener\">Matt Hill, da OneTreePlanted<\/a>, ou <a href=\"https:\/\/sustainablereview.com\/1-on-1-with-closed-loop-partners-ceo-ron-gonen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ron Gonen, da Closed Loop Partner<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p>Tive a sorte de conversar com o CEO da Upstream, Matt Prindiville. Durante nossa conversa, falamos sobre sustentabilidade versus mudan\u00e7a clim\u00e1tica, o poder dos setores p\u00fablico e privado, ESG, economias circulares, otimismo clim\u00e1tico racional e muito mais!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>A Upstream Solutions \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos fundada em 2003 com a miss\u00e3o de n\u00e3o apenas reduzir, mas tamb\u00e9m remover o pl\u00e1stico de uso \u00fanico do mundo. Sua organiza\u00e7\u00e3o encontra, fabrica e celebra solu\u00e7\u00f5es pr\u00e1ticas que ajudam pessoas, empresas e comunidades a mudar do uso \u00fanico para a reutiliza\u00e7\u00e3o. Nas \u00faltimas d\u00e9cadas, eles trabalharam com in\u00fameras organiza\u00e7\u00f5es comprometidas com um futuro mais sustent\u00e1vel.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Quando perguntado sobre as implica\u00e7\u00f5es futuras das mudan\u00e7as clim\u00e1ticas, Prindiville disse: &#8220;Sou um otimista. O que os cientistas est\u00e3o dizendo \u00e9, obviamente, muito assustador. Mas quando penso nas mudan\u00e7as que vi em minha carreira, \u00e9 incr\u00edvel o quanto j\u00e1 avan\u00e7amos. Daqui a dez anos, voc\u00ea ver\u00e1 que a responsabilidade ambiental e social ser\u00e1 a norma em todo o mundo.&#8221;<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Aprofunde-se \u2192 10 min<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":17,"featured_media":18503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3094],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"Tive a sorte de conversar com o CEO da Upstream, Matt Prindiville. Durante nossa conversa, falamos sobre sustentabilidade versus mudan\u00e7a clim\u00e1tica, o poder dos setores p\u00fablico e privado, ESG, economias circulares, otimismo clim\u00e1tico racional e muito mais!  A Upstream Solutions \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos fundada em 2003 com a miss\u00e3o de n\u00e3o apenas reduzir, mas tamb\u00e9m remover o pl\u00e1stico de uso \u00fanico do mundo. Sua organiza\u00e7\u00e3o encontra, fabrica e celebra solu\u00e7\u00f5es pr\u00e1ticas que ajudam pessoas, empresas e comunidades a mudar do uso \u00fanico para a reutiliza\u00e7\u00e3o. Nas \u00faltimas d\u00e9cadas, eles trabalharam com in\u00fameras organiza\u00e7\u00f5es comprometidas com um futuro mais sustent\u00e1vel.  Quando perguntado sobre as implica\u00e7\u00f5es futuras das mudan\u00e7as clim\u00e1ticas, Prindiville disse: &quot;Sou um otimista. O que os cientistas est\u00e3o dizendo \u00e9, obviamente, muito assustador. Mas quando penso nas mudan\u00e7as que vi em minha carreira, \u00e9 incr\u00edvel o quanto j\u00e1 avan\u00e7amos. Daqui a dez anos, voc\u00ea ver\u00e1 que a responsabilidade ambiental e social ser\u00e1 a norma em todo o mundo.&quot;  Aprofunde-se \u2192 10 min\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-28T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T17:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2499\" \/>\n\t<meta property=\"og:image:height\" content=\"2499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jared Wolf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/jar3dwolf\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jared Wolf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\"},\"author\":{\"name\":\"Jared Wolf\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\"},\"headline\":\"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas\",\"datePublished\":\"2022-07-28T13:00:00+00:00\",\"dateModified\":\"2024-08-10T17:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\"},\"wordCount\":3627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg\",\"articleSection\":[\"Estilo de vida\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\",\"name\":\"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg\",\"datePublished\":\"2022-07-28T13:00:00+00:00\",\"dateModified\":\"2024-08-10T17:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg\",\"width\":2499,\"height\":2499},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\",\"name\":\"Jared Wolf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1784129829\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1784129829\",\"caption\":\"Jared Wolf\"},\"description\":\"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.\",\"sameAs\":[\"https:\/\/www.instagram.com\/jrdwolf\",\"https:\/\/www.linkedin.com\/in\/jareddwolf\/\",\"https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf\",\"https:\/\/youtube.com\/sustainablereview\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/","og_locale":"pt_BR","og_type":"article","og_title":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review","og_description":"Tive a sorte de conversar com o CEO da Upstream, Matt Prindiville. Durante nossa conversa, falamos sobre sustentabilidade versus mudan\u00e7a clim\u00e1tica, o poder dos setores p\u00fablico e privado, ESG, economias circulares, otimismo clim\u00e1tico racional e muito mais!  A Upstream Solutions \u00e9 uma organiza\u00e7\u00e3o sem fins lucrativos fundada em 2003 com a miss\u00e3o de n\u00e3o apenas reduzir, mas tamb\u00e9m remover o pl\u00e1stico de uso \u00fanico do mundo. Sua organiza\u00e7\u00e3o encontra, fabrica e celebra solu\u00e7\u00f5es pr\u00e1ticas que ajudam pessoas, empresas e comunidades a mudar do uso \u00fanico para a reutiliza\u00e7\u00e3o. Nas \u00faltimas d\u00e9cadas, eles trabalharam com in\u00fameras organiza\u00e7\u00f5es comprometidas com um futuro mais sustent\u00e1vel.  Quando perguntado sobre as implica\u00e7\u00f5es futuras das mudan\u00e7as clim\u00e1ticas, Prindiville disse: \"Sou um otimista. O que os cientistas est\u00e3o dizendo \u00e9, obviamente, muito assustador. Mas quando penso nas mudan\u00e7as que vi em minha carreira, \u00e9 incr\u00edvel o quanto j\u00e1 avan\u00e7amos. Daqui a dez anos, voc\u00ea ver\u00e1 que a responsabilidade ambiental e social ser\u00e1 a norma em todo o mundo.\"  Aprofunde-se \u2192 10 min","og_url":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/","og_site_name":"Sustainable Review","article_published_time":"2022-07-28T13:00:00+00:00","article_modified_time":"2024-08-10T17:05:51+00:00","og_image":[{"width":2499,"height":2499,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg","type":"image\/jpeg"}],"author":"Jared Wolf","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/jar3dwolf","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Jared Wolf","Est. tempo de leitura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/"},"author":{"name":"Jared Wolf","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb"},"headline":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas","datePublished":"2022-07-28T13:00:00+00:00","dateModified":"2024-08-10T17:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/"},"wordCount":3627,"commentCount":0,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg","articleSection":["Estilo de vida"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/","url":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/","name":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg","datePublished":"2022-07-28T13:00:00+00:00","dateModified":"2024-08-10T17:05:51+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2022\/07\/MattPrindivilleHeadshot.jpg","width":2499,"height":2499},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/isto-e-o-que-um-diretor-executivo-de-uma-organizacao-sem-fins-lucrativos-diz-sobre-as-mudancas-climaticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Esta \u00e9 a opini\u00e3o de um CEO de uma organiza\u00e7\u00e3o sem fins lucrativos sobre as mudan\u00e7as clim\u00e1ticas"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb","name":"Jared Wolf","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1784129829","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1784129829","caption":"Jared Wolf"},"description":"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.","sameAs":["https:\/\/www.instagram.com\/jrdwolf","https:\/\/www.linkedin.com\/in\/jareddwolf\/","https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf","https:\/\/youtube.com\/sustainablereview"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/"}]}},"wpml_translations":{"en":"18226","pl":"60672","pt-br":"39367"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39367"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39367"}],"version-history":[{"count":2,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39367\/revisions"}],"predecessor-version":[{"id":59258,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39367\/revisions\/59258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/18503"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}