{"id":39399,"date":"2021-06-08T10:39:06","date_gmt":"2021-06-08T14:39:06","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39399"},"modified":"2024-08-10T13:07:17","modified_gmt":"2024-08-10T17:07:17","slug":"a-costa-de-jersey-tem-agua-limpa","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/","title":{"rendered":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto"},"content":{"rendered":"\n<p>Voc\u00ea acha que a costa de Jersey tem \u00e1gua limpa? Vamos dar uma olhada mais de perto.<\/p>\n\n\n\n<p>Para comemorar <a href=\"https:\/\/intltest.sustainablereview.com\/10-reasons-why-love-ocean\/\" target=\"_blank\" rel=\"noreferrer noopener\">a Semana Mundial dos Oceanos<\/a>, estamos lan\u00e7ando alguma luz sobre uma das costas mais visitadas dos Estados Unidos. A costa de Jersey recebe cerca de 48 milh\u00f5es de visitantes por ano. Com tantas pessoas lotando esse estado densamente povoado, os grupos ambientalistas de NJ apontam para s\u00e9rias preocupa\u00e7\u00f5es ambientais e de sa\u00fade em rela\u00e7\u00e3o \u00e0 \u00e1gua do oceano.<\/p>\n\n\n\n<div class=\"wp-block-group m0\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-text-color has-background has-primary-background-color has-primary-color is-style-wide\"\/>\n\n\n\n<h5 class=\"wp-block-heading\">Voc\u00ea est\u00e1 ocupado? Experimente a leitura r\u00e1pida.<\/h5>\n\n\n\n<p><strong>O furo de reportagem:<\/strong> O litoral de Jersey tem \u00e1gua limpa em compara\u00e7\u00e3o com muitas partes do pa\u00eds, mas algumas praias ainda s\u00e3o consideradas inseguras para banho em mais de 40% das vezes.<\/p>\n\n\n\n<p><strong>Principais causas da contamina\u00e7\u00e3o da \u00e1gua:<\/strong><\/p>\n\n\n\n<ul><li>sistemas de esgoto ultrapassados<\/li><li>desenvolvimento excessivo das orlas das praias<\/li><li>transbordamentos da agricultura industrial<\/li><li>escoamento de tempestades<\/li><\/ul>\n\n\n\n<p><strong>Conclus\u00e3o:<\/strong> A \u00e1gua da Costa de Jersey era muito mais suja h\u00e1 30 ou 40 anos. Mas algumas cidades da Costa de Jersey ainda precisam de muita ajuda para melhorar sua infraestrutura h\u00eddrica. Leia abaixo para saber como elas podem consertar isso.<\/p>\n\n\n\n<p><strong>Aprofunde-se \u2192 4 min<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-primary-background-color has-primary-color is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Relat\u00f3rio de \u00e1gua limpa de 2020<\/h2>\n\n\n\n<p>De acordo com o <a href=\"https:\/\/environmentnewjersey.org\/sites\/environment\/files\/reports\/Safe-for-Swimming_2020\/WEB_NJE_SafeForSwimming_2020.pdf\">relat\u00f3rio &#8220;Safe for Swimming&#8221; (Seguro para nadar<\/a> ) emitido pelo Environment New Jersey Research &amp; Policy Center, os n\u00edveis de bact\u00e9rias em 73 das 222 praias de Nova Jersey estudadas em 2019 foram considerados inseguros por pelo menos um dia.<\/p>\n\n\n\n<p>O culpado? Mat\u00e9ria fecal. A contamina\u00e7\u00e3o por esgoto, o estrume da agricultura industrial e o escoamento de superf\u00edcies pavimentadas contribuem para a \u00e1gua suja. A \u00e1gua impr\u00f3pria pode causar doen\u00e7as respirat\u00f3rias e gastrointestinais, bem como infec\u00e7\u00f5es no ouvido e nos olhos.<\/p>\n\n\n\n<p>O estudo observou que, em 2019, estima-se que 57 milh\u00f5es de casos de doen\u00e7as recreativas transmitidas pela \u00e1gua afetaram os nadadores dos EUA em oceanos, lagos, rios e lagoas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Legado da Lei da \u00c1gua Limpa<\/h2>\n\n\n\n<p><a href=\"https:\/\/intltest.sustainablereview.com\/clean-water-act-supreme-court\/\" target=\"_blank\" rel=\"noreferrer noopener\">A Lei da \u00c1gua Limpa de 1972<\/a> \u00e9 amplamente considerada uma das leis ambientais mais eficazes do pa\u00eds. Desde sua cria\u00e7\u00e3o em 1972, a CWA resistiu a in\u00fameras tentativas de enfraquecer suas regulamenta\u00e7\u00f5es, <strong> mas <\/strong>o que ela realmente faz?<\/p>\n\n\n\n<p>O governo federal aprovou a CWA para proteger as \u00e1guas americanas da polui\u00e7\u00e3o, garantindo que elas permane\u00e7am &#8220;pesc\u00e1veis e nad\u00e1veis&#8221;. Funcionalmente, ele exige que o setor (como agricultura, manufatura e empresas de petr\u00f3leo) receba uma licen\u00e7a para justificar a adi\u00e7\u00e3o de &#8220;qualquer poluente \u00e0s \u00e1guas naveg\u00e1veis de qualquer fonte pontual&#8221;.<\/p>\n\n\n\n<p>A fonte pontual refere-se \u00e0 fonte inicial da polui\u00e7\u00e3o. Parece bastante simples, n\u00e3o \u00e9? Pense novamente.<\/p>\n\n\n\n<p>A lei \u00e9 vulner\u00e1vel. Sua linguagem permanece vaga e as partes interessadas manipulam as interpreta\u00e7\u00f5es para atender \u00e0s suas necessidades. Os setores reconhecem essa vulnerabilidade, fazendo com que a CWA seja alvo de ataques frequentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A \u00e1gua da Costa de Jersey \u00e9 limpa?<\/h2>\n\n\n\n<p>Beachwood Beach West e Barnegat Light Bay Beach, no condado de Ocean, registraram os maiores \u00edndices de contamina\u00e7\u00e3o. Beachwood foi considerada insegura em 9 das 18 vezes em que foi testada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"601\" height=\"306\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/06\/jersey-shore-water-clean.png\" alt=\"clean water in the jersey shore\" class=\"wp-image-14983\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/jersey-shore-water-clean.png 601w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/jersey-shore-water-clean-300x153.png 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/jersey-shore-water-clean-45x23.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/jersey-shore-water-clean-500x255.png 500w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption><a href=\"https:\/\/environmentnewjersey.org\/sites\/environment\/files\/reports\/Safe-for-Swimming_2020\/WEB_NJE_SafeForSwimming_2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Meio ambiente de Nova Jersey<\/a><\/figcaption><\/figure><\/div>\n\n\n\n<p>Outros principais locais de praia por dias de nata\u00e7\u00e3o potencialmente inseguros no ver\u00e3o de 2019: Windward Beach, Harvey Cedars Borough em 75th Bay Front, Sea Girt Borough em New York Blvd, Wildwood City em Bennett, Surf City Borough em 16th St. Bay Front, Belmar Borough em L Street Beach, Belmar Borough em 20th, Long Branch City em Elberon Beach Club, Somers Point City em New Jersey Ave.<\/p>\n\n\n\n<p>Os condados de Cape May, Ocean e Monmouth tiveram, cada um, uma m\u00e9dia de 5% de dias com \u00e1gua insegura, enquanto o condado de Atlantic teve uma m\u00e9dia de apenas 1%.<\/p>\n\n\n\n<p>Em compara\u00e7\u00e3o com as d\u00e9cadas de 1970 e 80, Nova Jersey fez um tremendo progresso. Qualquer pessoa que tenha crescido em Nova Jersey (ou em qualquer \u00e1rea costeira) nesse per\u00edodo provavelmente se lembra dos frequentes fechamentos de praias e das condi\u00e7\u00f5es inseguras da \u00e1gua. Mas ainda h\u00e1 muito trabalho a ser feito.<\/p>\n\n\n\n<p>Em compara\u00e7\u00e3o com o resto do pa\u00eds, as condi\u00e7\u00f5es da \u00e1gua de Nova Jersey est\u00e3o muito bem classificadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"936\" height=\"557\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean.png\" alt=\"clean water in the united states\" class=\"wp-image-14984\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean.png 936w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean-300x179.png 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean-768x457.png 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean-45x27.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean-600x357.png 600w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/usa-clean-water-ocean-500x298.png 500w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption><a href=\"https:\/\/environmentnewjersey.org\/sites\/environment\/files\/reports\/Safe-for-Swimming_2020\/WEB_NJE_SafeForSwimming_2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Meio ambiente em Nova Jersey<\/a><\/figcaption><\/figure>\n\n\n\n<p>Partes do noroeste, como o Oregon, dos Grandes Lagos, como Ohio, e do sudeste, como o Texas, apresentam as condi\u00e7\u00f5es de \u00e1gua mais severas, onde nadar \u00e9 considerado inseguro em qualquer lugar, de 20% a 100% do tempo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que a \u00e1gua da Costa de Jersey nem sempre \u00e9 limpa<\/h2>\n\n\n\n<p>A agricultura industrial, o escoamento de \u00e1guas pluviais, o envelhecimento dos sistemas de esgoto e o desenvolvimento excessivo das praias contribuem para as condi\u00e7\u00f5es inseguras das \u00e1guas do litoral de Jersey.<\/p>\n\n\n\n<p>Com uma grande quantidade de propriedades \u00e0 beira-mar, o escoamento de casas contendo pesticidas, mat\u00e9ria fecal de animais de estima\u00e7\u00e3o etc. pode contribuir para a \u00e1gua suja. Quando ocorre uma tempestade, ela pode afetar gravemente as condi\u00e7\u00f5es da \u00e1gua por um longo per\u00edodo de tempo. Os sistemas de esgoto nos Estados Unidos tamb\u00e9m est\u00e3o se tornando obsoletos e, \u00e0 medida que a infraestrutura se torna mais delicada, ocorrem vazamentos que acabam nas \u00e1guas do oceano.<\/p>\n\n\n\n<p>A pecu\u00e1ria industrial tamb\u00e9m contribui significativamente para as condi\u00e7\u00f5es da \u00e1gua, onde a mat\u00e9ria fecal dos animais \u00e9 mal descartada e frequentemente acaba no oceano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como voc\u00ea pode ajudar<\/h2>\n\n\n\n<p>Apoie iniciativas locais, como a <a href=\"https:\/\/environmentnewjersey.org\/programs\/nje\/protect-jersey-shore-1\" target=\"_blank\" rel=\"noreferrer noopener\">Environment New Jersey<\/a> e a <a href=\"https:\/\/cleanoceanaction.org\/index.php?id=334\" target=\"_blank\" rel=\"noreferrer noopener\">Clean Ocean Action<\/a>, que exigem regulamenta\u00e7\u00e3o ambiental em \u00e1reas sens\u00edveis. Quanto mais pudermos limitar o desenvolvimento inseguro em \u00e1reas vulner\u00e1veis a \u00e1guas turvas, mais as pessoas (e a vida selvagem) poder\u00e3o desfrutar de \u00e1gua limpa.<\/p>\n\n\n\n<p>No ano passado, <a href=\"https:\/\/www.epa.gov\/newsreleases\/epa-awards-new-jersey-84-million-water-infrastructure-improvements\" target=\"_blank\" rel=\"noreferrer noopener\">a EPA concedeu a NJ US$ 84 milh\u00f5es<\/a> para melhorar a infraestrutura h\u00eddrica. Portanto, j\u00e1 existem algumas iniciativas em andamento. Na minha opini\u00e3o, o estado precisa de um pouco mais de press\u00e3o. Eles optaram por se concentrar mais em \u00e1gua pot\u00e1vel limpa em \u00e1reas urbanas, o que eu entendo perfeitamente. Mas garantir \u00e1gua limpa para o oceano na costa de Jersey tamb\u00e9m deve ser uma prioridade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p><strong>O furo de reportagem:<\/strong> Em compara\u00e7\u00e3o com muitas partes do pa\u00eds, a \u00e1gua de Jersey Shore \u00e9 limpa, mas algumas praias ainda s\u00e3o consideradas impr\u00f3prias para banho em mais de 40% das vezes.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Principais causas da contamina\u00e7\u00e3o da \u00e1gua:<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li>sistemas de esgoto ultrapassados<\/li>\n<li>desenvolvimento excessivo das orlas das praias<\/li>\n<li>transbordamentos da agricultura industrial<\/li>\n<li>escoamento de tempestades<\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Conclus\u00e3o:<\/strong> A \u00e1gua da Costa de Jersey era muito mais suja h\u00e1 30 ou 40 anos. Mas algumas cidades da Costa de Jersey ainda precisam de muita ajuda para melhorar sua infraestrutura h\u00eddrica. Leia abaixo para saber como elas podem consertar isso.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Aprofunde-se \u2192 4 min<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":17,"featured_media":14988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3091,3107],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"O furo de reportagem: Em compara\u00e7\u00e3o com muitas partes do pa\u00eds, a \u00e1gua de Jersey Shore \u00e9 limpa, mas algumas praias ainda s\u00e3o consideradas impr\u00f3prias para banho em mais de 40% das vezes.  Principais causas da contamina\u00e7\u00e3o da \u00e1gua:  sistemas de esgoto ultrapassadosdesenvolvimento excessivo das orlas das praiastransbordamentos da agricultura industrialescoamento de tempestades  Conclus\u00e3o: A \u00e1gua da Costa de Jersey era muito mais suja h\u00e1 30 ou 40 anos. Mas algumas cidades da Costa de Jersey ainda precisam de muita ajuda para melhorar sua infraestrutura h\u00eddrica. Leia abaixo para saber como elas podem consertar isso.  Aprofunde-se \u2192 4 min\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T14:39:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T17:07:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jared Wolf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/jar3dwolf\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jared Wolf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\"},\"author\":{\"name\":\"Jared Wolf\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\"},\"headline\":\"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto\",\"datePublished\":\"2021-06-08T14:39:06+00:00\",\"dateModified\":\"2024-08-10T17:07:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\"},\"wordCount\":1021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png\",\"articleSection\":[\"Energia e meio ambiente\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\",\"name\":\"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png\",\"datePublished\":\"2021-06-08T14:39:06+00:00\",\"dateModified\":\"2024-08-10T17:07:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png\",\"width\":1200,\"height\":800,\"caption\":\"clean water jersey shore\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\",\"name\":\"Jared Wolf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1783523900\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1783523900\",\"caption\":\"Jared Wolf\"},\"description\":\"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.\",\"sameAs\":[\"https:\/\/www.instagram.com\/jrdwolf\",\"https:\/\/www.linkedin.com\/in\/jareddwolf\/\",\"https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf\",\"https:\/\/youtube.com\/sustainablereview\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/","og_locale":"pt_BR","og_type":"article","og_title":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review","og_description":"O furo de reportagem: Em compara\u00e7\u00e3o com muitas partes do pa\u00eds, a \u00e1gua de Jersey Shore \u00e9 limpa, mas algumas praias ainda s\u00e3o consideradas impr\u00f3prias para banho em mais de 40% das vezes.  Principais causas da contamina\u00e7\u00e3o da \u00e1gua:  sistemas de esgoto ultrapassadosdesenvolvimento excessivo das orlas das praiastransbordamentos da agricultura industrialescoamento de tempestades  Conclus\u00e3o: A \u00e1gua da Costa de Jersey era muito mais suja h\u00e1 30 ou 40 anos. Mas algumas cidades da Costa de Jersey ainda precisam de muita ajuda para melhorar sua infraestrutura h\u00eddrica. Leia abaixo para saber como elas podem consertar isso.  Aprofunde-se \u2192 4 min","og_url":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/","og_site_name":"Sustainable Review","article_published_time":"2021-06-08T14:39:06+00:00","article_modified_time":"2024-08-10T17:07:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png","type":"image\/png"}],"author":"Jared Wolf","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/jar3dwolf","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Jared Wolf","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/"},"author":{"name":"Jared Wolf","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb"},"headline":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto","datePublished":"2021-06-08T14:39:06+00:00","dateModified":"2024-08-10T17:07:17+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/"},"wordCount":1021,"commentCount":0,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png","articleSection":["Energia e meio ambiente"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/","url":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/","name":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png","datePublished":"2021-06-08T14:39:06+00:00","dateModified":"2024-08-10T17:07:17+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/06\/Does-Jersey-Shore-have-Clean-Water.png","width":1200,"height":800,"caption":"clean water jersey shore"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/a-costa-de-jersey-tem-agua-limpa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"A costa de Jersey tem \u00e1gua limpa? Uma olhada mais de perto"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb","name":"Jared Wolf","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1783523900","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1783523900","caption":"Jared Wolf"},"description":"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.","sameAs":["https:\/\/www.instagram.com\/jrdwolf","https:\/\/www.linkedin.com\/in\/jareddwolf\/","https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf","https:\/\/youtube.com\/sustainablereview"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/"}]}},"wpml_translations":{"en":"14979","pl":"60704","pt-br":"39399"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39399"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39399"}],"version-history":[{"count":1,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39399\/revisions"}],"predecessor-version":[{"id":39911,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39399\/revisions\/39911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/14988"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}