{"id":39424,"date":"2021-01-04T12:50:34","date_gmt":"2021-01-04T17:50:34","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39424"},"modified":"2024-08-10T13:08:25","modified_gmt":"2024-08-10T17:08:25","slug":"sustentabilidade-em-2020","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/","title":{"rendered":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as"},"content":{"rendered":"\n<p>O ano passado ser\u00e1 considerado um dos anos de maior divis\u00e3o na hist\u00f3ria moderna. A humanidade, a contragosto, embaralhou o baralho e decidiu jogar um novo jogo. Centrada na pol\u00edtica atual e na recupera\u00e7\u00e3o econ\u00f4mica de curto prazo em 2020, a sustentabilidade perdeu a oportunidade de se tornar totalmente popular. Mas h\u00e1 motivos para voc\u00ea ter esperan\u00e7a.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Voc\u00ea est\u00e1 ocupado? Experimente a leitura r\u00e1pida.<\/h5>\n\n\n\n<p><strong>O furo de reportagem:<\/strong> A sustentabilidade em 2020 foi uma quest\u00e3o de transi\u00e7\u00e3o. Vamos fazer com que esta d\u00e9cada seja uma d\u00e9cada de mudan\u00e7as (n\u00e3o do tipo do F\u00f3rum Econ\u00f4mico Mundial&#8230; do tipo das pessoas comuns).<\/p>\n\n\n\n<p><strong>Principais tend\u00eancias de sustentabilidade em 2020:<\/strong><\/p>\n\n\n\n<ol><li>A economia se funde com o meio ambiente<ul><li>Aumento dos superfundos de ESG<\/li><li>A sustentabilidade social corporativa dispara<\/li><li>Aumento dos investimentos individuais sustent\u00e1veis<\/li><\/ul><\/li><li>A conscientiza\u00e7\u00e3o sobre o clima se torna predominante<ul><li>Os dados mostraram que a maioria dos americanos agora se preocupa com quest\u00f5es ambientais.<\/li><li>O clima entrou na pol\u00edtica nacional.<\/li><li>Os animais ganharam mais direitos &#8211; apoiados tanto pela ci\u00eancia quanto pela emo\u00e7\u00e3o.<\/li><\/ul><\/li><li>A comunidade clim\u00e1tica n\u00e3o consegue parar de brigar consigo mesma. Aqui est\u00e3o os diferentes tipos de ativistas:<ul><li>O otimista &#8220;N\u00e3o se preocupe, a ci\u00eancia e a tecnologia nos tirar\u00e3o dessa enrascada!&#8221;<\/li><li>O consumidor preocupado &#8220;Como podemos culpar as empresas se continuamos comprando seus produtos?&#8221;<\/li><li>O cidad\u00e3o preocupado &#8220;O problema n\u00e3o \u00e9 com os consumidores, \u00e9 com os cidad\u00e3os. Voc\u00ea precisa votar para fazer uma mudan\u00e7a real!&#8221;<\/li><li>O institucionalista &#8220;N\u00e3o importa o que os indiv\u00edduos fazem, a culpa \u00e9 dos governos e das corpora\u00e7\u00f5es.&#8221;<\/li><li>O apocal\u00edptico &#8220;Estamos ferrados, n\u00e3o importa o que aconte\u00e7a, Kathy. Comece a se preparar para a pr\u00f3xima Era do Gelo.&#8221;<\/li><li>O comprometido &#8220;Acho que Biden fez boas escolhas de gabinete para o clima&#8221;.<\/li><\/ul><ul><li>O radicalista &#8220;Se voc\u00ea dirige um carro a gasolina, n\u00e3o posso passar o Dia de A\u00e7\u00e3o de Gra\u00e7as com voc\u00ea.&#8221;<\/li><\/ul><\/li><\/ol>\n\n\n\n<p>Conclus\u00e3o<strong>:<\/strong> 2020 foi um ano misto para a sustentabilidade, mas estamos otimistas no longo prazo.<\/p>\n\n\n\n<p><strong>Aprofunde-se \u2192 7 min<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principais tend\u00eancias de sustentabilidade em 2020<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Sa\u00fade, economia e pol\u00edtica se fundem com o meio ambiente<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/01\/economy-environment-society-1024x768.png\" alt=\"\" class=\"wp-image-7822\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society-1024x768.png 1024w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society-300x225.png 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society-768x576.png 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society-45x34.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society-600x450.png 600w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/economy-environment-society.png 1280w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure>\n\n\n\n<p>Minha previs\u00e3o continua sendo a de que o legado da COVID ???????????? ser\u00e1 sobre sa\u00fade, ser\u00e1 econ\u00f4mico. E mostrar\u00e1 ao mundo como o meio ambiente coincide com a economia.<\/p>\n\n\n\n<p>\u00c9 claro que foram os pol\u00edticos e os cientistas que fecharam a sociedade. N\u00e3o foi o meio ambiente. Mas foi um alerta (que acontece a cada 10 a 20 anos) de que, em uma sociedade globalizada, algumas coisas est\u00e3o fora do nosso controle.<\/p>\n\n\n\n<p>Essas &#8220;coisas&#8221; \u00e0s vezes podem ser destrutivas. O meio ambiente \u00e9 uma dessas coisas.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Aqui est\u00e3o minhas previs\u00f5es para o legado da COVID-19 (a partir de mar\u00e7o de 2020):<\/h5>\n\n\n\n<p><em>1) Menos empresas a longo prazo.<br><br>Big biz vai \u2191 Mom-and-Pop vai \u2193<br><br>A maioria das empresas que est\u00e3o falindo no momento tem menos de 50 funcion\u00e1rios. As lojas que sobrevivem s\u00e3o as que t\u00eam uma carteira grande o suficiente para suportar o golpe.<br><br>Quantas pequenas e m\u00e9dias empresas restar\u00e3o quando tudo isso for dito e feito?<br><br>2) <a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?keywords=inequality&amp;highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6647291231166611456\"> A<\/a> partir de 1, <a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?keywords=inequality&amp;highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6647291231166611456\"> a #Inequality<\/a> ser\u00e1 pior do que nunca.<br><br>As pessoas que est\u00e3o perdendo seus neg\u00f3cios, seus empregos, suas economias? A hist\u00f3ria mostra que a maioria delas ser\u00e1 empurrada para baixo na escala social.<br><br>3) O uso de dinheiro vivo diminuir\u00e1 ainda mais \u00e0 medida que as solu\u00e7\u00f5es de pagamento digital continuarem a crescer.<br><br>O dinheiro vivo \u00e9 sujo, ineficiente e aparentemente antiquado. Esse pode ser o primeiro ponto de discuss\u00e3o para que o mundo acabe com o dinheiro.<br><br>???????????? ???????????????????????? ????????????????????????? Oportunidade. Talvez ainda n\u00e3o tenhamos chegado l\u00e1, mas a situa\u00e7\u00e3o est\u00e1 come\u00e7ando a se parecer cada vez mais com 2007-8 a cada dia. Podemos romper o 1 e o 2 aprendendo com o passado.<\/em><\/p>\n\n\n\n<p>O dinheiro, mais especificamente a capacidade de fazer uma transa\u00e7\u00e3o an\u00f4nima, \u00e9 um elemento necess\u00e1rio de uma sociedade livre. As criptomoedas esperam servir a esse prop\u00f3sito, mas a conex\u00e3o com a Internet necess\u00e1ria para fazer transa\u00e7\u00f5es torna tudo menos descentralizado. Por enquanto, o dinheiro ainda ter\u00e1 um prop\u00f3sito. Mas, com o passar do tempo, o acesso \u00e0 Internet pode se tornar um direito fundamental.<\/p>\n\n\n\n<p>Isso est\u00e1 ligado \u00e0 rela\u00e7\u00e3o entre o impacto social e a economia. Assim como as not\u00edcias sobre vacinas influenciam o mercado de a\u00e7\u00f5es atualmente, a percep\u00e7\u00e3o do p\u00fablico sobre o clima pode um dia acompanhar as tend\u00eancias econ\u00f4micas. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Impacto da COVID no futuro<\/h4>\n\n\n\n<p>Sei que n\u00e3o fui a \u00fanica voz na Internet a pensar em sociedade sem dinheiro e desigualdade em meados de mar\u00e7o. Ainda assim, essas previs\u00f5es est\u00e3o envelhecendo bem&#8230; para o bem ou para o mal.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=PKHHZ_zmTHI<\/div><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.msn.com\/en-in\/news\/world\/covid-19-pandemic-has-put-265-million-people-at-risk-of-starvation-study\/ar-BB152HIv\" target=\"_blank\" rel=\"noreferrer noopener\">265 milh\u00f5es de pessoas correm agora o risco de passar fome<\/a> devido \u00e0 *resposta pol\u00edtica* \u00e0 COVID-19.<\/p>\n\n\n\n<p>Acho que o mais convincente \u00e9 a ideia de que a COVID n\u00e3o durar\u00e1 para sempre. Se voc\u00ea se comportar como se fosse o fim do mundo, as pessoas que estavam planejando o futuro com calma passar\u00e3o por voc\u00ea.<\/p>\n\n\n\n<p>A discuss\u00e3o sobre se a crise da COVID-19 tem mais a ver com sa\u00fade ou pol\u00edtica e economia \u00e9 trivial. O que realmente importa \u00e9 que as institui\u00e7\u00f5es em geral est\u00e3o se identificando novamente de forma a priorizar as metas ambientais, sociais e de governan\u00e7a (ESG) pela primeira vez.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Essa tend\u00eancia de fazer o bem corporativo \u00e9 mera sinaliza\u00e7\u00e3o de virtude ou ter\u00e1 um impacto real?<\/h5>\n\n\n\n<p>Essa \u00e9 a minha principal preocupa\u00e7\u00e3o com rela\u00e7\u00e3o \u00e0 sustentabilidade no futuro. A ideia de que muitas empresas poderiam se preocupar menos com florestas exuberantes e mais com a redu\u00e7\u00e3o de custos para satisfazer as partes interessadas.<\/p>\n\n\n\n<p>Se pudermos fazer uma apresenta\u00e7\u00e3o bonita com metas para 2030, eles continuar\u00e3o comprando nossos produtos. Mas, como escrevi em meu <a href=\"https:\/\/intltest.sustainablereview.com\/sustainable-small-business\/\" target=\"_blank\" rel=\"noreferrer noopener\">guia de pequenas empresas sustent\u00e1veis<\/a>, os consumidores est\u00e3o ficando mais espertos. A era de ouro da lavagem verde est\u00e1 desaparecendo \u00e0 medida que as m\u00eddias sociais amadurecem e facilitam a den\u00fancia.<\/p>\n\n\n\n<p>Em 2021 e nos anos seguintes, \u00e0 medida que os superfundos de ESG e as start-ups de sustentabilidade se tornarem a norma, os vigilantes e os \u00f3rg\u00e3os reguladores das empresas se tornar\u00e3o cada vez mais importantes para garantir a estabilidade. Ningu\u00e9m precisa de outro crash das empresas pontocom.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais <a href=\"https:\/\/intltest.sustainablereview.com\/sustainable-investing\/\" target=\"_blank\" rel=\"noreferrer noopener\">investimentos sustent\u00e1veis<\/a><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"796\" height=\"424\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/01\/sustainable-investing-share.jpg\" alt=\"\" class=\"wp-image-7827\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/sustainable-investing-share.jpg 796w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/sustainable-investing-share-300x160.jpg 300w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/sustainable-investing-share-768x409.jpg 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/sustainable-investing-share-45x24.jpg 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/sustainable-investing-share-600x320.jpg 600w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><figcaption><a class=\"svq-fancy-img\" href=\"https:\/\/www.visualcapitalist.com\/wp-content\/uploads\/2017\/08\/sustainable-investing-share.jpg\" target=\"_blank\" rel=\"noreferrer noopener\">Capitalista visual<\/a><\/figcaption><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Como escrevi em abril de 2020:<\/h5>\n\n\n\n<p><em><a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?keywords=sustainability&amp;highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6654041469449498624\">A #sustentabilidade<\/a> estava ganhando muita for\u00e7a no mundo dos investimentos antes do surto. Tanto que os \u00f3rg\u00e3os reguladores agora est\u00e3o preocupados com o fato de que colocar um r\u00f3tulo de <a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?keywords=sustainable&amp;highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6654041469449498624\">#sustent\u00e1vel<\/a> em um fundo \u00e9 muito parecido com colocar um r\u00f3tulo de pontocom em 2000.<br><br>Agora estamos em um impasse. Sim, a M\u00e3e Natureza est\u00e1 tendo uma folga, mas isso \u00e9 tempor\u00e1rio. Na busca incessante por solu\u00e7\u00f5es inovadoras para as quest\u00f5es ambientais, ser\u00e1 que podemos nos dar ao luxo de perder um ano? Meus <a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?keywords=thursdaythoughts&amp;highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6654041469449498624\">#thursdaythoughts<\/a>:<br><br>Acho que a verdadeira quest\u00e3o \u00e9 se a nossa &#8220;volta ao normal&#8221; equivale a um aumento global da produ\u00e7\u00e3o em n\u00edveis sem precedentes. Se recuperar o atraso econ\u00f4mico significa priorizar a produ\u00e7\u00e3o em detrimento da efici\u00eancia, ent\u00e3o n\u00e3o perdemos apenas um ano, mas retrocedemos dez.<br><br>O v\u00edrus nos mostrou mais um exemplo da fragilidade do nosso sistema. Se a pr\u00e1tica do bem social for exclu\u00edda de seu plano de neg\u00f3cios de longo prazo, voc\u00ea n\u00e3o tem um plano de longo prazo. Algumas das maiores mentes em finan\u00e7as &#8211; <a href=\"https:\/\/www.linkedin.com\/in\/ACoAABAkIqcBTdNVYPXdjiIPOUV8rT5j4TTieko\">Larry Fink<\/a> <a href=\"https:\/\/www.linkedin.com\/in\/ACoAAAlvPzIB9698ovjCXze-oHTH7gP12lYYmn8\">, David M. Solomon<\/a> &#8211; est\u00e3o nos dizendo que &#8220;risco clim\u00e1tico \u00e9 risco de investimento&#8221;.<br><br>Corra com os primeiros adaptadores ou perca-se na maioria tardia.<\/em><\/p>\n\n\n\n<p>Voc\u00ea pode saber mais sobre <a href=\"https:\/\/intltest.sustainablereview.com\/sustainable-investing\/\" target=\"_blank\" rel=\"noreferrer noopener\">investimentos sustent\u00e1veis aqui<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aumento da conscientiza\u00e7\u00e3o sobre o clima e os animais<\/h3>\n\n\n\n<p>A maioria dos americanos reconhece a mudan\u00e7a clim\u00e1tica e quer que o governo fa\u00e7a mais para ajudar.<\/p>\n\n\n\n<p>Talvez seja o ativismo, talvez seja a maior cobertura da m\u00eddia, talvez seja o amadurecimento das gera\u00e7\u00f5es mais jovens, talvez sejam os inc\u00eandios florestais, talvez sejam as vozes cient\u00edficas mais altas&#8230; o resultado final \u00e9 que mais pessoas est\u00e3o conscientes do clima. Mesmo em um ano dominado pela histeria da sa\u00fade p\u00fablica.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"634\" height=\"904\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/01\/pew-research-center.png\" alt=\"\" class=\"wp-image-7837\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/pew-research-center.png 634w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/pew-research-center-210x300.png 210w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/pew-research-center-45x64.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/pew-research-center-600x856.png 600w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure><\/div>\n\n\n\n<p>Os direitos dos animais tamb\u00e9m est\u00e3o mais presentes agora. Essa \u00e9 uma grande tend\u00eancia para a sustentabilidade em 2020.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"1024\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-511x1024.png\" alt=\"sustainability in 2020 demonstrated by animal welfare laws by country\" class=\"wp-image-6387\" srcset=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-511x1024.png 511w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-150x300.png 150w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-768x1540.png 768w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-766x1536.png 766w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-1021x2048.png 1021w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-45x90.png 45w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-1320x2647.png 1320w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1-600x1203.png 600w, https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/09\/1288-animal-welfare-laws-1.png 2161w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/><\/figure><\/div>\n\n\n\n<p>Acredito firmemente que <a href=\"https:\/\/intltest.sustainablereview.com\/sustainability-starts-with-animals\/\" target=\"_blank\" rel=\"noreferrer noopener\">a sustentabilidade come\u00e7a com a maneira como tratamos os animais.<\/a> &lt;&#8211; mais reflex\u00f5es sobre os animais. Aqui est\u00e1 o porqu\u00ea.<\/p>\n\n\n\n<p>Et\u00f3logos como <a href=\"https:\/\/www.linkedin.com\/in\/ACoAAAvOBtcB3MCcPWgdXX9oqqIQmHDXu0ZOslI\">Jonathan Balcombe<\/a>, autor de &#8220;What A Fish Knows&#8221; (O que um peixe sabe), est\u00e3o lentamente desmascarando os mitos sobre a intelig\u00eancia animal. As percep\u00e7\u00f5es ultrapassadas que o homem tem de nossos primos subaqu\u00e1ticos e florestais est\u00e3o vindo \u00e0 tona \u00e0 medida que a ci\u00eancia concreta encontra a PETA branda.<br><br>Os animais s\u00e3o seres sens\u00edveis. Isso n\u00e3o \u00e9 um romance, \u00e9 o mundo em que vivemos. Os animais experimentam uma ampla gama de emo\u00e7\u00f5es. Os pitag\u00f3ricos acreditavam que os animais experimentavam a mesma gama de emo\u00e7\u00f5es que os humanos.<br><br>E a ci\u00eancia mostra cada vez mais evid\u00eancias convincentes de que, para muitos animais, isso pode ser verdade. Isso inclui medo, alegria, felicidade, vergonha, constrangimento, ressentimento, ci\u00fame, raiva, ira, amor&#8230;<br><br>Atualmente, a maioria das na\u00e7\u00f5es avan\u00e7adas n\u00e3o reconhece os animais como seres sencientes. E esperamos que estilos de vida sustent\u00e1veis sejam amplamente adotados em nossas casas? Voc\u00ea precisa aprender a dirigir um carro antes de levantar o cap\u00f4 para consert\u00e1-lo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">POV: Estado da comunidade clim\u00e1tica<\/h3>\n\n\n\n<p>Na semana passada, no reddit, perguntei ao canal #climateoffensive qual era o principal problema da comunidade clim\u00e1tica. Isso provocou uma conversa bastante interessante e um lembrete importante sobre a variedade de prioridades e prop\u00f3sitos que encontramos no ecl\u00e9tico grupo de seres humanos ecologicamente conscientes.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Aqui est\u00e1 meu problema n\u00famero 1 (no momento) com a sustentabilidade em 2020:<\/h5>\n\n\n\n<p>\u00c9 muito preocupante o quanto estamos dispostos a criticar uns aos outros quando discordamos.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"269\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/01\/diversity-greatest-strength.gif\" alt=\"\" class=\"wp-image-7828\"\/><\/figure>\n\n\n\n<p>Por exemplo, no passado, critiquei a ret\u00f3rica clim\u00e1tica do dia do ju\u00edzo final. Pessoalmente, n\u00e3o acho que isso seja produtivo quando se tenta convencer algu\u00e9m a assumir um papel de ativista.<\/p>\n\n\n\n<p>O que acontece com voc\u00ea? Adolescentes ansiosos e idosos cansados. At\u00e9 criei um blog para tentar despolitizar as conversas sobre o clima.<\/p>\n\n\n\n<p>Adivinhe o que voc\u00ea acha? \u00c9 UMA OPINI\u00c3O.<\/p>\n\n\n\n<p>N\u00e3o sou inculto. N\u00e3o sou um agente de desinforma\u00e7\u00e3o. Eu amo os animais e amo a Terra. E, em \u00faltima an\u00e1lise, quero o que \u00e9 melhor para ela. Se eu estiver errado sobre como fazer isso, tudo bem tamb\u00e9m.<\/p>\n\n\n\n<p>Estou sempre disposto a ouvir algu\u00e9m e mudar de ideia.<\/p>\n\n\n\n<p>\u00c9 importante lembrar que n\u00e3o h\u00e1 uma solu\u00e7\u00e3o \u00fanica para as mudan\u00e7as clim\u00e1ticas&#8230; n\u00e3o h\u00e1 uma ideia que seja facilmente alcan\u00e7\u00e1vel no atual sistema global corrupto em que nos encontramos.<\/p>\n\n\n\n<p>A maioria dos pol\u00edticos e l\u00edderes empresariais est\u00e1 comprometida. Ningu\u00e9m quer abrir m\u00e3o de seu pequeno poder tempor\u00e1rio como locat\u00e1rios, criadores e destruidores neste navio azul-esverdeado.<\/p>\n\n\n\n<p>Ser\u00e1 necess\u00e1ria a vontade das massas para for\u00e7\u00e1-los a mudar. Talvez isso exija assustar o p\u00fablico, talvez esse n\u00e3o seja o melhor m\u00e9todo.<\/p>\n\n\n\n<p>Nesse meio tempo, vamos entender que todos n\u00f3s (o p\u00fablico preocupado com o clima) temos um objetivo comum: um futuro mais saud\u00e1vel e feliz.<\/p>\n\n\n\n<p>Antes de criticar algu\u00e9m por uma ideia n\u00e3o convencional, muitas das quais eu tenho, por que n\u00e3o tentamos ser um pouco menos cr\u00edticos e um pouco mais comunicativos? Afinal, 100 empresas s\u00e3o realmente culpadas ????.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Aqui est\u00e3o algumas perspectivas diferentes dos comentaristas:<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">O otimista:<\/h5>\n\n\n\n<p><em>Admito que fico frustrado quando parece que h\u00e1 algum tipo de progresso na energia verde e isso geralmente \u00e9 respondido com &#8220;bem, nunca ser\u00e1 suficiente<\/em><\/p>\n\n\n\n<p><em>os pequenos passos s\u00e3o importantes! Isso faz parte da normaliza\u00e7\u00e3o dessas coisas, do envolvimento de mais pessoas, de mais aten\u00e7\u00e3o e financiamento, da promo\u00e7\u00e3o. N\u00e3o acho que isso se limite apenas a grupos baseados no clima, vejo muito dessa ideia quase purista de &#8220;tudo ou nada&#8221; em grupos de defesa.<\/em><\/p>\n\n\n\n<p><em>Mas \u00e9 muito desanimador o fato de haver uma tend\u00eancia de &#8220;se n\u00e3o for resolvido exatamente dessa forma, n\u00e3o serve<\/em><\/p>\n\n\n\n<p><em>Do jeito que est\u00e1, n\u00e3o teremos um meio moralmente claro de consertar as coisas. \u00c9 chato e muito dif\u00edcil, mas as coisas est\u00e3o cinzentas e bagun\u00e7adas agora. Temos que aceitar, conviver e comemorar as pequenas coisas que se acumulam.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O consumidor preocupado:<\/h5>\n\n\n\n<p><em>Vejo muita culpa apontada para as corpora\u00e7\u00f5es e como n\u00f3s, o povo, somos impotentes para fazer qualquer coisa quando as empresas petroqu\u00edmicas e as multinacionais continuam a fazer o que fazem para obter lucro.<\/em><\/p>\n\n\n\n<p><em>Quase como se elas n\u00e3o dependessem de n\u00f3s, os consumidores, que optamos repetidamente por comprar seus servi\u00e7os e produtos.<\/em><\/p>\n\n\n\n<p><em>Elas sabem que, independentemente de seu hist\u00f3rico, derramamentos ambientais, destrui\u00e7\u00e3o do meio ambiente, aumento das emiss\u00f5es l\u00edquidas, elas sabem que o cliente tem mem\u00f3ria curta e amanh\u00e3 estar\u00e1 exigindo os pre\u00e7os mais baratos de energia, os melhores e mais novos aparelhos e outro Big Mac.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O cidad\u00e3o preocupado:<\/h5>\n\n\n\n<p><em>N\u00e3o acho que isso recaia sobre n\u00f3s, consumidores, mas sim sobre n\u00f3s, cidad\u00e3os. <a href=\"https:\/\/en.wikiversity.org\/wiki\/10_Principles_of_Economics#7._Government_can_sometimes_improve_market_outcomes\" rel=\"noreferrer noopener\" target=\"_blank\">A externalidade faz com que o mercado falhe, e somente os governos podem consertar isso<\/a>. Como mesmo as melhores pol\u00edticas raramente s\u00e3o aprovadas por si mesmas, cabe a n\u00f3s, como cidad\u00e3os, fazer algo a respeito. <a href=\"https:\/\/np.reddit.com\/r\/TrueReddit\/comments\/kmttr9\/watching_earth_burn\/ghhsevs\/\" rel=\"noreferrer noopener\" target=\"_blank\">Aqui est\u00e3o algumas coisas que eu<\/a> fiz, se algu\u00e9m estiver procurando ideias.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O institucionalista:<\/h5>\n\n\n\n<p><em>O ativismo do lado do consumidor n\u00e3o funciona. A \u00fanica coisa que funciona \u00e9 a mudan\u00e7a sist\u00eamica, que exige legisla\u00e7\u00e3o por parte dos governos. O que \u00e9 basicamente o que ILikeNeurons disse 5 horas antes de mim. A responsabilidade n\u00e3o \u00e9 nossa como consumidores, mas como cidad\u00e3os.<\/em><\/p>\n\n\n\n<p><em>Exemplo: voc\u00ea pode parar de comer carne hoje, e talvez consiga convencer alguns amigos a segui-lo. Mas voc\u00ea nunca vai convencer os outros a comer carne. Mas voc\u00ea nunca convencer\u00e1 a grande maioria dos consumidores a parar de consumir. Eles precisam ser for\u00e7ados a parar por meio da aprova\u00e7\u00e3o de leis que limitem o consumo.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O apocal\u00edptico:<\/h5>\n\n\n\n<p><em>Evitamos falar sobre os piores cen\u00e1rios poss\u00edveis. Constantemente.<\/em><\/p>\n\n\n\n<p><em>Isso \u00e9 incrivelmente irritante. Adivinhe s\u00f3, lutamos para impedir um aumento de 2 a 4 graus na temperatura global antes do ano 2100. Esse \u00e9 o objetivo, eu entendo.<\/em><\/p>\n\n\n\n<p>Mas h\u00e1 uma chance acima de 1% de um aumento de 8 graus dentro do mesmo per\u00edodo de tempo<em> se muitas coisas derem errado e se multiplicarem.<\/em><\/p>\n\n\n\n<p><em>Isso seria a extin\u00e7\u00e3o absoluta da ra\u00e7a humana.<\/em><\/p>\n\n\n\n<p><em>\u00c9 um evento improv\u00e1vel, mas totalmente poss\u00edvel.<\/em><\/p>\n\n\n\n<p><em>E n\u00e3o falamos sobre isso porque seria &#8220;alarmista&#8221;.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O comprometedor:<\/h5>\n\n\n\n<p><em>A principal coisa que me incomoda \u00e9 o radicalismo. Se voc\u00ea for muito radical, ningu\u00e9m o ouvir\u00e1, exceto outros radicais. Voc\u00ea pode ser radical em sua mente e em suas cren\u00e7as, mas isso n\u00e3o o ajudar\u00e1 a convencer ningu\u00e9m que j\u00e1 n\u00e3o esteja do seu lado a ficar do seu lado.<\/em><\/p>\n\n\n\n<p><em>\u00c9 a mesma ideia para todos os t\u00f3picos, todos os debates pol\u00edticos. Seja gentil, n\u00e3o culpe, a culpa n\u00e3o \u00e9 de uma \u00fanica pessoa. Na verdade, acredito que as conversas sobre o assunto devem come\u00e7ar de forma simples e amig\u00e1vel, at\u00e9 que as pessoas comecem a ficar intrigadas e queiram saber mais.<\/em><\/p>\n\n\n\n<p><em>Mas amea\u00e7as contra as pessoas ou amea\u00e7as sobre o fim do mundo apenas fazem as pessoas revirarem os olhos. Foi isso que me transformou em um negacionista do clima no ensino m\u00e9dio. E eu era assim at\u00e9 fazer um curso na faculdade sobre sustentabilidade.<\/em> <em>Era puramente informativo, interessante e intrigante.<\/em><\/p>\n\n\n\n<p><em>N\u00e3o houve declara\u00e7\u00f5es radicais ou raiva no aprendizado. Era apenas: aqui est\u00e3o os fatos e voc\u00ea vai pensar sobre eles. E eu pensei sobre isso, por anos. Depois decidi voltar para a faculdade e aprender mais sobre o assunto e me apaixonar totalmente por ele.<\/em><\/p>\n\n\n\n<p><em>Mas garanto a voc\u00ea que nada do que foi dito no notici\u00e1rio, por Greta Thunberg ou por ativistas pol\u00edticos teria me feito dar a m\u00ednima para o assunto.<\/em><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">O radicalista<\/h5>\n\n\n\n<p><em>Falta de radicaliza\u00e7\u00e3o em rela\u00e7\u00e3o a problemas radicais.<\/em><\/p>\n\n\n\n<p><em>Voc\u00ea sente que n\u00e3o pode comprometer sua moral, apesar do fato de que h\u00e1 um imperativo moral para ajustar a estrat\u00e9gia quando o resultado n\u00e3o leva \u00e0 justi\u00e7a.<\/em><\/p>\n\n\n\n<p><em>Como no caso do problema do bonde, que \u00e9 um dilema moral sobre a troca de trilhos para salvar mais vidas, \u00e9 menos prov\u00e1vel que as pessoas fa\u00e7am a mesma troca se, em vez de trocar de trilhos, voc\u00ea estiver intencionalmente empurrando algu\u00e9m para os trilhos para descarril\u00e1-los.<\/em><\/p>\n\n\n\n<p><em>Supere seus sentimentos ou voc\u00ea n\u00e3o conseguir\u00e1 salvar ningu\u00e9m, muito menos a humanidade, de seus pr\u00f3prios processos de autodestrui\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<p><em>Isso \u00e9 tudo o que tenho a dizer.<\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ent\u00e3o&#8230; h\u00e1 muitas perspectivas diferentes. Podemos respeitar isso?<\/h4>\n\n\n\n<p>Pare de se identificar com r\u00f3tulos. Veja voc\u00ea como um ponto infinito de consci\u00eancia interagindo com outros pontos infinitos de consci\u00eancia.<\/p>\n\n\n\n<p>Posso ser um libert\u00e1rio vegano preocupado com o clima hoje, mas um judeu de Nova Jersey jogando golfe amanh\u00e3. N\u00e3o sou casado com nenhum r\u00f3tulo.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"270\" src=\"https:\/\/intltest.sustainablereview.com\/\/wp-content\/uploads\/2021\/01\/subculture.gif\" alt=\"\" class=\"wp-image-7830\"\/><\/figure>\n\n\n\n<p>Decidi compartilhar partes desse t\u00f3pico de coment\u00e1rios do Reddit para demonstrar como existem muitos tipos diferentes de cidad\u00e3os preocupados com o clima. Colocar a comunidade do clima\/sustentabilidade em um \u00fanico grupo n\u00e3o \u00e9 apenas improdutivo, mas tamb\u00e9m enganoso.<\/p>\n\n\n\n<p>At\u00e9 mesmo um colono superconservador no meio do pa\u00eds faz parte da comunidade em algum aspecto. Eles provavelmente s\u00e3o mais &#8220;sustent\u00e1veis&#8221; do que voc\u00ea, que tem 28 anos e mora no Brooklyn.<\/p>\n\n\n\n<p>Em vez de julgar algu\u00e9m que v\u00ea o mundo de forma diferente de voc\u00ea, respeite o fato de que todos n\u00f3s temos uma coisa em comum: o compromisso com um ecossistema mais saud\u00e1vel e feliz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sustentabilidade al\u00e9m de 2020<\/h2>\n\n\n\n<p>A sustentabilidade em 2020 tinha tudo a ver com transi\u00e7\u00e3o. Quer\u00edamos fazer a transi\u00e7\u00e3o das economias, das estrat\u00e9gias corporativas, dos empregos, dos lares, da educa\u00e7\u00e3o e dos estilos de vida sociais.<\/p>\n\n\n\n<p>A sustentabilidade para al\u00e9m de 2020, rumo a 2021, deve ser uma quest\u00e3o de a\u00e7\u00e3o.<\/p>\n\n\n\n<p>O movimento clim\u00e1tico est\u00e1 assumindo a lideran\u00e7a nessa frente. \u00c9 hora de as empresas substitu\u00edrem as metas por pol\u00edticas. <a href=\"https:\/\/intltest.sustainablereview.com\/voting-matters-climate-change\/\" target=\"_blank\" rel=\"noreferrer noopener\">Os pol\u00edticos locais podem fazer mudan\u00e7as b\u00e1sicas<\/a> nos munic\u00edpios que causam impacto real.<\/p>\n\n\n\n<p>Por mais que eu zombe da pol\u00edtica da Calif\u00f3rnia, veja o que Los Angeles conseguiu realizar localmente contra a polui\u00e7\u00e3o&#8230; em 30 anos. Para isso, voc\u00ea precisou de muitas pessoas no local.<\/p>\n\n\n\n<p>Vamos levar esse impulso at\u00e9 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:heading {\"level\":5} --><\/p>\n<h5>Se voc\u00ea estiver ocupado, experimente a leitura r\u00e1pida.<\/h5>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>O furo de reportagem:<\/strong> A sustentabilidade em 2020 foi uma quest\u00e3o de transi\u00e7\u00e3o. Vamos fazer com que esta d\u00e9cada seja de mudan\u00e7as (n\u00e3o do tipo do F\u00f3rum Econ\u00f4mico Mundial&#8230; do tipo das pessoas comuns).<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Principais tend\u00eancias de sustentabilidade em 2020:<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list {\"ordered\":true} --><\/p>\n<ol>\n<li>A economia se funde com o meio ambiente\n<ul>\n<li>Aumento dos superfundos de ESG<\/li>\n<li>A sustentabilidade social corporativa dispara<\/li>\n<li>Aumento dos investimentos individuais sustent\u00e1veis<\/li>\n<\/ul>\n<\/li>\n<li>A conscientiza\u00e7\u00e3o sobre o clima se torna predominante\n<ul>\n<li>Os dados mostraram que a maioria dos americanos agora se preocupa com quest\u00f5es ambientais.<\/li>\n<li>O clima entrou na pol\u00edtica nacional.<\/li>\n<li>Os animais ganharam mais direitos &#8211; apoiados tanto pela ci\u00eancia quanto pela emo\u00e7\u00e3o.<\/li>\n<\/ul>\n<\/li>\n<li>A comunidade clim\u00e1tica n\u00e3o consegue parar de brigar consigo mesma. Aqui est\u00e3o os diferentes tipos de ativistas:\n<ul>\n<li>O otimista &#8220;N\u00e3o se preocupe, a ci\u00eancia e a tecnologia nos tirar\u00e3o dessa enrascada!&#8221;<\/li>\n<li>O consumidor preocupado &#8220;Como podemos culpar as empresas se continuamos comprando seus produtos?&#8221;<\/li>\n<li>O cidad\u00e3o preocupado &#8220;O problema n\u00e3o \u00e9 com os consumidores, \u00e9 com os cidad\u00e3os. Voc\u00ea precisa votar para fazer uma mudan\u00e7a real!&#8221;<\/li>\n<li>O institucionalista &#8220;N\u00e3o importa o que os indiv\u00edduos fazem, a culpa \u00e9 dos governos e das corpora\u00e7\u00f5es.&#8221;<\/li>\n<li>O apocal\u00edptico &#8220;Estamos ferrados, n\u00e3o importa o que aconte\u00e7a, Kathy. Comece a se preparar para a pr\u00f3xima Era do Gelo.&#8221;<\/li>\n<li>O comprometido &#8220;Acho que Biden fez boas escolhas de gabinete para o clima&#8221;.<\/li>\n<\/ul>\n<ul>\n<li>O radicalista &#8220;Se voc\u00ea dirige um carro a gasolina, n\u00e3o posso passar o Dia de A\u00e7\u00e3o de Gra\u00e7as com voc\u00ea.&#8221;<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Conclus\u00e3o<strong>:<\/strong> 2020 foi um ano misto para a sustentabilidade, mas estamos otimistas no longo prazo.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Aprofunde-se \u2192 7 min<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":17,"featured_media":7833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3094],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea estiver ocupado, experimente a leitura r\u00e1pida.  O furo de reportagem: A sustentabilidade em 2020 foi uma quest\u00e3o de transi\u00e7\u00e3o. Vamos fazer com que esta d\u00e9cada seja de mudan\u00e7as (n\u00e3o do tipo do F\u00f3rum Econ\u00f4mico Mundial... do tipo das pessoas comuns).  Principais tend\u00eancias de sustentabilidade em 2020:  A economia se funde com o meio ambienteAumento dos superfundos de ESGA sustentabilidade social corporativa disparaAumento dos investimentos individuais sustent\u00e1veisA conscientiza\u00e7\u00e3o sobre o clima se torna predominanteOs dados mostraram que a maioria dos americanos agora se preocupa com quest\u00f5es ambientais.O clima entrou na pol\u00edtica nacional.Os animais ganharam mais direitos - apoiados tanto pela ci\u00eancia quanto pela emo\u00e7\u00e3o.A comunidade clim\u00e1tica n\u00e3o consegue parar de brigar consigo mesma. Aqui est\u00e3o os diferentes tipos de ativistas:O otimista &quot;N\u00e3o se preocupe, a ci\u00eancia e a tecnologia nos tirar\u00e3o dessa enrascada!&quot;O consumidor preocupado &quot;Como podemos culpar as empresas se continuamos comprando seus produtos?&quot;O cidad\u00e3o preocupado &quot;O problema n\u00e3o \u00e9 com os consumidores, \u00e9 com os cidad\u00e3os. Voc\u00ea precisa votar para fazer uma mudan\u00e7a real!&quot;O institucionalista &quot;N\u00e3o importa o que os indiv\u00edduos fazem, a culpa \u00e9 dos governos e das corpora\u00e7\u00f5es.&quot;O apocal\u00edptico &quot;Estamos ferrados, n\u00e3o importa o que aconte\u00e7a, Kathy. Comece a se preparar para a pr\u00f3xima Era do Gelo.&quot;O comprometido &quot;Acho que Biden fez boas escolhas de gabinete para o clima&quot;.O radicalista &quot;Se voc\u00ea dirige um carro a gasolina, n\u00e3o posso passar o Dia de A\u00e7\u00e3o de Gra\u00e7as com voc\u00ea.&quot;  Conclus\u00e3o: 2020 foi um ano misto para a sustentabilidade, mas estamos otimistas no longo prazo.  Aprofunde-se \u2192 7 min\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T17:50:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T17:08:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jared Wolf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@http:\/\/twitter.com\/jar3dwolf\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jared Wolf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\"},\"author\":{\"name\":\"Jared Wolf\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\"},\"headline\":\"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as\",\"datePublished\":\"2021-01-04T17:50:34+00:00\",\"dateModified\":\"2024-08-10T17:08:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\"},\"wordCount\":3226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png\",\"articleSection\":[\"Estilo de vida\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\",\"name\":\"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png\",\"datePublished\":\"2021-01-04T17:50:34+00:00\",\"dateModified\":\"2024-08-10T17:08:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png\",\"width\":1600,\"height\":1256,\"caption\":\"Sustainability in 2020 overview\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb\",\"name\":\"Jared Wolf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1778073921\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1778073921\",\"caption\":\"Jared Wolf\"},\"description\":\"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.\",\"sameAs\":[\"https:\/\/www.instagram.com\/jrdwolf\",\"https:\/\/www.linkedin.com\/in\/jareddwolf\/\",\"https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf\",\"https:\/\/youtube.com\/sustainablereview\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/","og_locale":"pt_BR","og_type":"article","og_title":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review","og_description":"Se voc\u00ea estiver ocupado, experimente a leitura r\u00e1pida.  O furo de reportagem: A sustentabilidade em 2020 foi uma quest\u00e3o de transi\u00e7\u00e3o. Vamos fazer com que esta d\u00e9cada seja de mudan\u00e7as (n\u00e3o do tipo do F\u00f3rum Econ\u00f4mico Mundial... do tipo das pessoas comuns).  Principais tend\u00eancias de sustentabilidade em 2020:  A economia se funde com o meio ambienteAumento dos superfundos de ESGA sustentabilidade social corporativa disparaAumento dos investimentos individuais sustent\u00e1veisA conscientiza\u00e7\u00e3o sobre o clima se torna predominanteOs dados mostraram que a maioria dos americanos agora se preocupa com quest\u00f5es ambientais.O clima entrou na pol\u00edtica nacional.Os animais ganharam mais direitos - apoiados tanto pela ci\u00eancia quanto pela emo\u00e7\u00e3o.A comunidade clim\u00e1tica n\u00e3o consegue parar de brigar consigo mesma. Aqui est\u00e3o os diferentes tipos de ativistas:O otimista \"N\u00e3o se preocupe, a ci\u00eancia e a tecnologia nos tirar\u00e3o dessa enrascada!\"O consumidor preocupado \"Como podemos culpar as empresas se continuamos comprando seus produtos?\"O cidad\u00e3o preocupado \"O problema n\u00e3o \u00e9 com os consumidores, \u00e9 com os cidad\u00e3os. Voc\u00ea precisa votar para fazer uma mudan\u00e7a real!\"O institucionalista \"N\u00e3o importa o que os indiv\u00edduos fazem, a culpa \u00e9 dos governos e das corpora\u00e7\u00f5es.\"O apocal\u00edptico \"Estamos ferrados, n\u00e3o importa o que aconte\u00e7a, Kathy. Comece a se preparar para a pr\u00f3xima Era do Gelo.\"O comprometido \"Acho que Biden fez boas escolhas de gabinete para o clima\".O radicalista \"Se voc\u00ea dirige um carro a gasolina, n\u00e3o posso passar o Dia de A\u00e7\u00e3o de Gra\u00e7as com voc\u00ea.\"  Conclus\u00e3o: 2020 foi um ano misto para a sustentabilidade, mas estamos otimistas no longo prazo.  Aprofunde-se \u2192 7 min","og_url":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/","og_site_name":"Sustainable Review","article_published_time":"2021-01-04T17:50:34+00:00","article_modified_time":"2024-08-10T17:08:25+00:00","og_image":[{"width":1600,"height":1256,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png","type":"image\/png"}],"author":"Jared Wolf","twitter_card":"summary_large_image","twitter_creator":"@http:\/\/twitter.com\/jar3dwolf","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Jared Wolf","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/"},"author":{"name":"Jared Wolf","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb"},"headline":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as","datePublished":"2021-01-04T17:50:34+00:00","dateModified":"2024-08-10T17:08:25+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/"},"wordCount":3226,"commentCount":0,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png","articleSection":["Estilo de vida"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/","url":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/","name":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png","datePublished":"2021-01-04T17:50:34+00:00","dateModified":"2024-08-10T17:08:25+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2021\/01\/Sustainability-in-2020-1.png","width":1600,"height":1256,"caption":"Sustainability in 2020 overview"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/sustentabilidade-em-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Sustentabilidade em 2020: Um ano de oportunidades perdidas, novas esperan\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/9aab44dc72cd3c3d0bae867ca5bdf3bb","name":"Jared Wolf","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1778073921","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/5fdad557a37518fdc60e28cf27e8dbaa.jpg?ver=1778073921","caption":"Jared Wolf"},"description":"I am a marketer, content creator, and climate change optimist committed to demystifying sustainability. I have published over 150 articles spanning climate and sustainability, dedicating his time to crafting scientifically-accurate, apolitical content around sensitive climate topics. My content is designed to create a healthier, happier climate conversation through earth-conscious, honest independent media.","sameAs":["https:\/\/www.instagram.com\/jrdwolf","https:\/\/www.linkedin.com\/in\/jareddwolf\/","https:\/\/x.com\/http:\/\/twitter.com\/jar3dwolf","https:\/\/youtube.com\/sustainablereview"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/jared\/"}]}},"wpml_translations":{"en":"7813","pl":"60729","pt-br":"39424"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39424"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39424"}],"version-history":[{"count":1,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39424\/revisions"}],"predecessor-version":[{"id":39936,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39424\/revisions\/39936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/7833"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}