{"id":39485,"date":"2020-06-08T13:38:15","date_gmt":"2020-06-08T17:38:15","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39485"},"modified":"2024-08-10T13:12:59","modified_gmt":"2024-08-10T17:12:59","slug":"baleias-enormes-sumidouros-de-carbono","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/","title":{"rendered":"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Quando se trata de salvar o planeta, uma baleia vale mais do que milhares de \u00e1rvores.&#8221;<\/p>\n<cite>&#8211; Fundo Monet\u00e1rio Internacional (FMI)<\/cite><\/blockquote>\n\n\n\n<p>Feliz Dia Mundial dos Oceanos!<\/p>\n\n\n\n<p>O Dia Mundial dos Oceanos foi criado pelas <a href=\"https:\/\/unworldoceansday.org\/\">Na\u00e7\u00f5es<\/a> Unidas para disseminar a conscientiza\u00e7\u00e3o sobre o papel essencial dos oceanos em nossas vidas di\u00e1rias, defender a gest\u00e3o sustent\u00e1vel dos recursos marinhos e incentivar a prote\u00e7\u00e3o de nossos oceanos. Os oceanos recebem pouca aten\u00e7\u00e3o no quebra-cabe\u00e7a da mudan\u00e7a clim\u00e1tica, mas precisamos abordar como salvar os organismos de nossos oceanos em r\u00e1pido aquecimento da amea\u00e7a de perigo cr\u00edtico e extin\u00e7\u00e3o. O combate \u00e0s mudan\u00e7as clim\u00e1ticas far\u00e1 com que o oceano retorne gradualmente \u00e0s temperaturas normais e habit\u00e1veis que permitem que esses organismos se desenvolvam.<\/p>\n\n\n\n<p>Recentemente, estudos demonstraram que podemos curar nossos oceanos de dentro para fora. A solu\u00e7\u00e3o? As baleias, especialmente as grandes baleias. A elabora\u00e7\u00e3o de um plano para proteger as baleias em todo o mundo poderia <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">reduzir os gases de efeito estufa e diminuir o aquecimento global<\/a>, de acordo com o Fundo Monet\u00e1rio Internacional.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/IYumJGmwiW09M8uTNfoLu0b0po4eLPwUROt9TsjAmmFlUn0qlKUcgQL0IxZk8WsWWD7FHFoByZ4z_HOWXh2E8LN4U7RXXEOHwPuaDJ-zHHWwjXvM2a-R6ZXj8wKtqn4MZyi198UR\" alt=\"whales coming out of ocean\"\/><\/figure>\n\n\n\n<p><em>Cortesia de Michael Fishbach e da Biblioteca do Condado de Las Vegas-Clark<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como as baleias podem ajudar a reduzir<\/strong><strong> as concentra\u00e7\u00f5es<\/strong><strong>atmosf\u00e9ricas<\/strong> de<strong><sub>CO2<\/sub><\/strong><strong>?<\/strong><\/h3>\n\n\n\n<p>\u00c0 medida que as concentra\u00e7\u00f5es atmosf\u00e9ricas de di\u00f3xido de carbono aumentam, os pesquisadores trabalham fervorosamente para construir e testar maneiras de reduzi-las manualmente. Entretanto, muitos desses m\u00e9todos s\u00e3o de alta tecnologia, caros e <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">n\u00e3o testados<\/a>. As baleias oferecem uma op\u00e7\u00e3o digna <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">, &#8220;sem tecnologia&#8221; e<\/a> baseada na terra, que evita qualquer dano imprevisto causado por abordagens de alta tecnologia.<\/p>\n\n\n\n<p>As baleias acumulam carbono continuamente ao longo de suas vidas e o levam consigo para o fundo do oceano quando morrem, removendo completamente o carbono da atmosfera <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">por s\u00e9culos<\/a>. Quanto<sub>CO2 <\/sub>elas carregam com elas, voc\u00ea pode perguntar? Uma m\u00e9dia de <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\"><em>33 toneladas<\/em><\/a>. Para fins de compara\u00e7\u00e3o, uma \u00e1rvore m\u00e9dia absorve apenas <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">48 libras<\/a> por ano, o que faz com que a prote\u00e7\u00e3o das baleias seja, sem d\u00favida, uma ferramenta mais eficaz para combater as mudan\u00e7as clim\u00e1ticas do que o plantio de \u00e1rvores.<\/p>\n\n\n\n<p>Como se essas estat\u00edsticas n\u00e3o fossem surpreendentes o suficiente, as baleias t\u00eam um efeito indireto, mas surpreendentemente poderoso, sobre o<sub>consumo <\/sub>externo<sub>de CO2 <\/sub>. As baleias estimulam o crescimento do fitopl\u00e2ncton em todos os lugares por onde passam, secretando nutrientes para o fitopl\u00e2ncton<a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">(principalmente ferro e nitrog\u00eanio<\/a>) em seus res\u00edduos. Na chamada <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">&#8220;bomba de baleia&#8221;,<\/a> as baleias trazem esses nutrientes para a superf\u00edcie quando migram e sobem \u00e0 superf\u00edcie para respirar.<\/p>\n\n\n\n<p>Da mesma forma, o fitopl\u00e2ncton fornece no m\u00ednimo <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">50% do oxig\u00eanio atmosf\u00e9rico global<\/a> e faz isso de forma extremamente ben\u00e9fica. Eles liberam cerca de <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\"><em>37 bilh\u00f5es de<\/em> toneladas m\u00e9tricas de<sub>CO2 &#8211; cerca de<\/sub><\/a> <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">40% da produ\u00e7\u00e3o total de di\u00f3xido de carbono &#8211;<\/a>para criar esse oxig\u00eanio. Gra\u00e7as \u00e0s baleias, elas t\u00eam todos os nutrientes de que precisam para alimentar esse poderoso processo que salva o planeta.<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/Rv27iVNp1dOG0VwvSPr1rjPO5ofgZqiZxOFnG3GFWJLSv9pj9hWHc6Ofl_Y-zbXzP36cj_bb7Lca4lujIndYqckzyypUcT1DwtziB_Mz5LOgIictuJB3ApG1eQWGffzTk6v35TDN\" alt=\"\"\/><figcaption class=\"wp-element-caption\"><em>\u00a9 GRID-Arendal 2019<\/em><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Hist\u00f3ria da ca\u00e7a \u00e0 baleia<\/strong><\/h2>\n\n\n\n<p>Ao longo da hist\u00f3ria, as baleias foram valorizadas por outros atributos al\u00e9m de suas habilidades de absor\u00e7\u00e3o de carbono. Os noruegueses come\u00e7aram a ca\u00e7ar baleias h\u00e1 <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">4.000 anos<\/a> e integraram as baleias \u00e0 sua cultura e aos seus meios de subsist\u00eancia. Eles usavam todas as partes da baleia: comiam <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">carne,<\/a> gordura <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">, pele e \u00f3rg\u00e3os<\/a> para obter prote\u00edna, gordura e nutrientes; reaproveitavam a barbatana, a estrutura oral de filtragem das baleias, para fazer <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">cestas, linha de pesca e material para telhados<\/a>; e esculpiam os ossos em <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">ferramentas e m\u00e1scaras cerimoniais<\/a>.<\/p>\n\n\n\n<p>Na Idade M\u00e9dia e na Renascen\u00e7a, o \u00f3leo de baleia impulsionou as economias europeias quando os europeus come\u00e7aram a usar o \u00f3leo de baleia &#8211; a secre\u00e7\u00e3o da <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">gordura das baleias francas e das baleias-cabe\u00e7udas e da cavidade da cabe\u00e7a dos cachalotes &#8211; como<\/a>combust\u00edvel para l\u00e2mpadas a \u00f3leo. Os americanos tamb\u00e9m dependiam do \u00f3leo de baleia para acender suas lamparinas. Eles tamb\u00e9m usavam ossos de baleia como estrutura para <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">espartilhos e saias de argolas<\/a>. No entanto, a confiabilidade dos combust\u00edveis f\u00f3sseis, como o querosene e o petr\u00f3leo, acabou por destruir o setor de \u00f3leo de baleia.<\/p>\n\n\n\n<p>Os Estados Unidos s\u00e3o culpados pela ca\u00e7a excessiva de baleias, especialmente no s\u00e9culo XIX. O setor baleeiro contribuiu com milh\u00f5es de d\u00f3lares para a economia dos EUA, e a frota baleeira americana armada com arp\u00f5es invadiu as \u00e1guas do \u00c1rtico e da Ant\u00e1rtica em busca desses preciosos mam\u00edferos. De acordo com alguns cientistas, mais baleias foram mortas no in\u00edcio do s\u00e9culo XX do que nos <a href=\"https:\/\/iwc.int\/home#:~:text=The%20International%20Whaling%20Commission%20(IWC,since%20its%20establishment%20in%201946.\">quatro s\u00e9culos anteriores<\/a>. Os Estados Unidos proibiram a ca\u00e7a \u00e0s baleias em 1971, depois de <a href=\"https:\/\/www.nationalgeographic.org\/article\/big-fish-history-whaling\/\">incluir oito baleias na lista de esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p>A <a href=\"https:\/\/iwc.int\/home\">Comiss\u00e3o Baleeira Internacional<\/a> (IWC), composta por <a href=\"https:\/\/iwc.int\/home#:~:text=The%20International%20Whaling%20Commission%20(IWC,since%20its%20establishment%20in%201946.\">88 pa\u00edses<\/a> em todo o mundo e depositada nos Estados Unidos, exigiu a <a href=\"https:\/\/theintltest.sustainablereview.com\/earth-week\/1980s-hansen-climate-change\">suspens\u00e3o da ca\u00e7a comercial de baleias em 1982<\/a>. A Noruega e o Jap\u00e3o votaram contra a pol\u00edtica e, atualmente, esses dois pa\u00edses ainda ca\u00e7am algumas baleias para carne e pesquisa.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/vimeo.com\/395549323<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Conserva\u00e7\u00e3o de baleias nos EUA e na Europa atualmente<\/strong><\/h2>\n\n\n\n<p>Atualmente, o n\u00famero de baleias \u00e9 de aproximadamente <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">1,3 milh\u00e3o<\/a>, e os esfor\u00e7os de conserva\u00e7\u00e3o para que elas voltem \u00e0 sua popula\u00e7\u00e3o <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">de 4 a 5 milh\u00f5es<\/a> antes da ca\u00e7a \u00e0s baleias poderiam reduzir significativamente o efeito estufa, diminuindo o di\u00f3xido de carbono atmosf\u00e9rico. Isso poderia aumentar a atividade do fitopl\u00e2ncton em pelo menos <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">um por cento<\/a>, estimulando centenas de milh\u00f5es de toneladas de absor\u00e7\u00e3o de<sub>CO2<\/sub>. Em geral, as baleias vivem mais de <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\">60 anos<\/a>, e um aumento substancial da popula\u00e7\u00e3o traria benef\u00edcios imediatos e duradouros.<\/p>\n\n\n\n<p>As baleias s\u00e3o mortas mensalmente depois de se enroscarem em redes de pesca, consumirem pl\u00e1stico oce\u00e2nico e sofrerem impactos de navios e polui\u00e7\u00e3o sonora, embora a ca\u00e7a comercial de baleias tenha sido significativamente reduzida. Para reviver suas popula\u00e7\u00f5es, \u00e9 necess\u00e1rio alavancar incentivos econ\u00f4micos equivalentes aos seus valores econ\u00f4micos de captura de carbono.<\/p>\n\n\n\n\n\n<!--nextpage-->\n\n\n\n<h2 class=\"wp-block-heading\">Combatendo as mudan\u00e7as clim\u00e1ticas com as baleias<\/h2>\n\n\n\n<p>Entre uma combina\u00e7\u00e3o de<a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\"> ecoturismo, sequestro de carbono, aprimoramento da pesca<\/a> e valores de precifica\u00e7\u00e3o de carbono, uma baleia-franca t\u00edpica vale mais de <a href=\"https:\/\/www.imf.org\/external\/pubs\/ft\/fandd\/2019\/12\/natures-solution-to-climate-change-chami.htm#:~:text=The%20carbon%20capture%20potential%20of,of%20the%20atmosphere%20for%20centuries.\"> US$ 2 milh\u00f5es<\/a>. Subsidiar as empresas de navega\u00e7\u00e3o para que ajustem suas rotas de passagem a fim de evitar colis\u00f5es com baleias poderia reduzir a grande trag\u00e9dia dos bens comuns que existe nesses gentis gigantes.<\/p>\n\n\n\n<p>Al\u00e9m disso, os governos podem financiar esfor\u00e7os e pesquisas de limpeza de pl\u00e1sticos nos oceanos, e organiza\u00e7\u00f5es como a <a href=\"https:\/\/www.thegef.org\/\">Global Environment Facility<\/a> podem apoiar financeiramente pa\u00edses de baixa renda que podem ter dificuldade em sustentar os esfor\u00e7os de socorro \u00e0s baleias.<\/p>\n\n\n\n<p>Da mesma forma, Ralph Chami, diretor assistente do Instituto de Desenvolvimento de Capacidades do FMI, entende que para levar os formuladores de pol\u00edticas \u00e0 a\u00e7\u00e3o <a href=\"https:\/\/www.nationalgeographic.com\/environment\/2019\/09\/how-much-is-a-whale-worth\/\">&#8220;que n\u00e3o acreditam em salvar animais s\u00f3 por salvar&#8221;<\/a> \u00e9 necess\u00e1rio monetizar as baleias. Chami observa: &#8220;Temos que concordar que as baleias s\u00e3o um bem p\u00fablico internacional&#8221;.<\/p>\n\n\n\n<p>Recuperar a popula\u00e7\u00e3o global de baleias at\u00e9 a metade de seu tamanho original n\u00e3o \u00e9 tarefa f\u00e1cil, mas devemos fazer tudo o que estiver ao nosso alcance para multiplicar as popula\u00e7\u00f5es de esp\u00e9cies de baleias em todos os oceanos da Terra. Independentemente de uma ferramenta de sequestro de carbono de alta tecnologia se tornar amplamente dispon\u00edvel, o aproveitamento do poder de captura de carbono dessas belas criaturas sempre melhorar\u00e1 positivamente nossa atmosfera e os ecossistemas marinhos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p><strong>As bal<\/strong> eias-francas acumulam carbono ao longo de sua vida e morrem com ele no fundo do oceano. Assim, cada uma delas salva cerca de 33 toneladas de carbono da atmosfera.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Por que isso \u00e9 importante<\/strong> Atualmente, o n\u00famero de baleias \u00e9 de aproximadamente 1,3 milh\u00e3o, e os esfor\u00e7os de conserva\u00e7\u00e3o para que elas voltem \u00e0 popula\u00e7\u00e3o de 4 a 5 milh\u00f5es antes da ca\u00e7a \u00e0s baleias poderiam reduzir significativamente o efeito estufa, diminuindo o di\u00f3xido de carbono atmosf\u00e9rico. No entanto, elas est\u00e3o constantemente sob a amea\u00e7a de serem ca\u00e7adas.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Panorama geral<\/strong> Recuperar a popula\u00e7\u00e3o global de baleias at\u00e9 a metade de seu tamanho original n\u00e3o \u00e9 tarefa f\u00e1cil, mas devemos fazer tudo o que estiver ao nosso alcance para multiplicar as popula\u00e7\u00f5es de esp\u00e9cies de baleias em todos os oceanos da Terra. Independentemente de uma ferramenta de sequestro de carbono de alta tecnologia se tornar amplamente dispon\u00edvel, o aproveitamento do poder de captura de carbono dessas belas criaturas sempre melhorar\u00e1 positivamente nossa atmosfera e os ecossistemas marinhos.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Aprofunde-se &#8211;&gt; 3 min de leitura<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":7,"featured_media":2602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3108,3078,3101,3091,3086,3097],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\" \/>\n<link rel=\"next\" href=\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"As bal eias-francas acumulam carbono ao longo de sua vida e morrem com ele no fundo do oceano. Assim, cada uma delas salva cerca de 33 toneladas de carbono da atmosfera.  Por que isso \u00e9 importante Atualmente, o n\u00famero de baleias \u00e9 de aproximadamente 1,3 milh\u00e3o, e os esfor\u00e7os de conserva\u00e7\u00e3o para que elas voltem \u00e0 popula\u00e7\u00e3o de 4 a 5 milh\u00f5es antes da ca\u00e7a \u00e0s baleias poderiam reduzir significativamente o efeito estufa, diminuindo o di\u00f3xido de carbono atmosf\u00e9rico. No entanto, elas est\u00e3o constantemente sob a amea\u00e7a de serem ca\u00e7adas.  Panorama geral Recuperar a popula\u00e7\u00e3o global de baleias at\u00e9 a metade de seu tamanho original n\u00e3o \u00e9 tarefa f\u00e1cil, mas devemos fazer tudo o que estiver ao nosso alcance para multiplicar as popula\u00e7\u00f5es de esp\u00e9cies de baleias em todos os oceanos da Terra. Independentemente de uma ferramenta de sequestro de carbono de alta tecnologia se tornar amplamente dispon\u00edvel, o aproveitamento do poder de captura de carbono dessas belas criaturas sempre melhorar\u00e1 positivamente nossa atmosfera e os ecossistemas marinhos.  Aprofunde-se --&gt; 3 min de leitura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T17:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T17:12:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Riley DeBaecke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Riley DeBaecke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\"},\"author\":{\"name\":\"Riley DeBaecke\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/5bd12f601000453f3b0e8f61f5b6cda5\"},\"headline\":\"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono\",\"datePublished\":\"2020-06-08T17:38:15+00:00\",\"dateModified\":\"2024-08-10T17:12:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\"},\"wordCount\":1328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png\",\"articleSection\":[\"\u00c1gua\",\"Animais\",\"Ci\u00eancia\",\"Energia e meio ambiente\",\"Mudan\u00e7as clim\u00e1ticas\",\"Planeta\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\",\"name\":\"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png\",\"datePublished\":\"2020-06-08T17:38:15+00:00\",\"dateModified\":\"2024-08-10T17:12:59+00:00\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png\",\"width\":3000,\"height\":2000,\"caption\":\"whales fighting climate change\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/5bd12f601000453f3b0e8f61f5b6cda5\",\"name\":\"Riley DeBaecke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/2a5d013a1c79391e152d14bdefab74dd.jpg?ver=1778568177\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/2a5d013a1c79391e152d14bdefab74dd.jpg?ver=1778568177\",\"caption\":\"Riley DeBaecke\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/riley-debaecke-53b080192\/\"],\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/rileyd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/","next":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/2\/","og_locale":"pt_BR","og_type":"article","og_title":"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review","og_description":"As bal eias-francas acumulam carbono ao longo de sua vida e morrem com ele no fundo do oceano. Assim, cada uma delas salva cerca de 33 toneladas de carbono da atmosfera.  Por que isso \u00e9 importante Atualmente, o n\u00famero de baleias \u00e9 de aproximadamente 1,3 milh\u00e3o, e os esfor\u00e7os de conserva\u00e7\u00e3o para que elas voltem \u00e0 popula\u00e7\u00e3o de 4 a 5 milh\u00f5es antes da ca\u00e7a \u00e0s baleias poderiam reduzir significativamente o efeito estufa, diminuindo o di\u00f3xido de carbono atmosf\u00e9rico. No entanto, elas est\u00e3o constantemente sob a amea\u00e7a de serem ca\u00e7adas.  Panorama geral Recuperar a popula\u00e7\u00e3o global de baleias at\u00e9 a metade de seu tamanho original n\u00e3o \u00e9 tarefa f\u00e1cil, mas devemos fazer tudo o que estiver ao nosso alcance para multiplicar as popula\u00e7\u00f5es de esp\u00e9cies de baleias em todos os oceanos da Terra. Independentemente de uma ferramenta de sequestro de carbono de alta tecnologia se tornar amplamente dispon\u00edvel, o aproveitamento do poder de captura de carbono dessas belas criaturas sempre melhorar\u00e1 positivamente nossa atmosfera e os ecossistemas marinhos.  Aprofunde-se --&gt; 3 min de leitura","og_url":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/","og_site_name":"Sustainable Review","article_published_time":"2020-06-08T17:38:15+00:00","article_modified_time":"2024-08-10T17:12:59+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change-1024x683.png","type":"image\/png"}],"author":"Riley DeBaecke","twitter_card":"summary_large_image","twitter_creator":"@sustainreview","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Riley DeBaecke","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/"},"author":{"name":"Riley DeBaecke","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/5bd12f601000453f3b0e8f61f5b6cda5"},"headline":"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono","datePublished":"2020-06-08T17:38:15+00:00","dateModified":"2024-08-10T17:12:59+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/"},"wordCount":1328,"commentCount":0,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png","articleSection":["\u00c1gua","Animais","Ci\u00eancia","Energia e meio ambiente","Mudan\u00e7as clim\u00e1ticas","Planeta"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/","url":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/","name":"A maravilha das baleias: as baleias s\u00e3o grandes sumidouros de carbono &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png","datePublished":"2020-06-08T17:38:15+00:00","dateModified":"2024-08-10T17:12:59+00:00","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/baleias-enormes-sumidouros-de-carbono\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/whales-fighting-climate-change.png","width":3000,"height":2000,"caption":"whales fighting climate change"},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/5bd12f601000453f3b0e8f61f5b6cda5","name":"Riley DeBaecke","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/2a5d013a1c79391e152d14bdefab74dd.jpg?ver=1778568177","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/2a5d013a1c79391e152d14bdefab74dd.jpg?ver=1778568177","caption":"Riley DeBaecke"},"sameAs":["https:\/\/www.linkedin.com\/in\/riley-debaecke-53b080192\/"],"url":"https:\/\/sustainablereview.com\/pt-br\/author\/rileyd\/"}]}},"wpml_translations":{"en":"3760","pl":"60790","pt-br":"39485"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39485"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39485"}],"version-history":[{"count":1,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39485\/revisions"}],"predecessor-version":[{"id":39997,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39485\/revisions\/39997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/2602"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}