{"id":39491,"date":"2020-05-22T01:16:00","date_gmt":"2020-05-22T05:16:00","guid":{"rendered":"https:\/\/sustainablereview.com\/?p=39491"},"modified":"2024-08-10T13:13:28","modified_gmt":"2024-08-10T17:13:28","slug":"pessoas-menos-e-mais-compras-de-verao-verdes","status":"publish","type":"post","link":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/","title":{"rendered":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o"},"content":{"rendered":"\n<p>De canetas ecologicamente corretas a t\u00eanis de origem sustent\u00e1vel, os mercados atuais est\u00e3o inundados com os chamados produtos &#8220;ecologicamente corretos&#8221;. Seu p\u00fablico-alvo? Consumidores adultos jovens que est\u00e3o entrando em um mundo atormentado simultaneamente pelo <a href=\"https:\/\/www.resilience.org\/stories\/2013-07-25\/the-high-price-of-materialism\/\">materialismo voraz<\/a> e pelos graves efeitos da <a href=\"https:\/\/www.nature.com\/articles\/d41586-019-03595-0\">mudan\u00e7a clim\u00e1tica<\/a>(quase) <a href=\"https:\/\/www.nature.com\/articles\/d41586-019-03595-0\">irrevers\u00edvel<\/a>. <\/p>\n\n\n\n<p>O mantra de marketing &#8220;compre verde&#8221; convida os consumidores a gastar um pouco mais para se sentirem um pouco menos culpados por sua contribui\u00e7\u00e3o pessoal para a degrada\u00e7\u00e3o do meio ambiente.<\/p>\n\n\n\n<p>Mas se n\u00e3o estamos mudando nosso estilo de vida e n\u00e3o estamos realmente reduzindo nosso consumo geral, quanto bem estamos realmente fazendo? A compra verde permite que os compradores reduzam a culpa enquanto consomem em seu ritmo habitual.<\/p>\n\n\n\n<p>Como um jovem consumidor que est\u00e1 lutando com essa quest\u00e3o de comprar verde ou simplesmente comprar menos, decidi me aprofundar na pesquisa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O &#8220;efeito do consumo verde<\/strong><\/h2>\n\n\n\n<p>O argumento a favor da compra verde \u00e9 que a compra ou o uso de um produto ecologicamente correto cria um <a href=\"https:\/\/www.sciencedaily.com\/releases\/2019\/12\/191205130605.htm\">&#8220;brilho caloroso&#8221;<\/a> nos consumidores, gerando um sentimento de satisfa\u00e7\u00e3o semelhante \u00e0 emo\u00e7\u00e3o que voc\u00ea sente ao ajudar os outros. Um estudo da Concordia University descobriu que o consumo de um produto sustent\u00e1vel pode levar a uma maior <a href=\"https:\/\/www.concordia.ca\/news\/stories\/2019\/12\/03\/concordia-research-shows-that-using-green-products-leads-to-a-warm-glow-in-shoppers.html\">sensa\u00e7\u00e3o de prazer<\/a>.<\/p>\n\n\n\n<p>Ent\u00e3o, voc\u00ea deve considerar essa evid\u00eancia como um sinal verde para comprar aquele quinto par de cal\u00e7as de ioga? Talvez n\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O materialismo verde ainda \u00e9 materialismo<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=oGab38pKscw<\/div><\/figure>\n\n\n\n<p>Os resultados de outro <a href=\"https:\/\/more.sohe.wisc.edu\/wp-content\/uploads\/2017\/05\/Helm-S.-Serido-J.-Ahn-S.-Y.-Ligon-V.-Shim-S.-2019.-Materialist-values-financial-and-pro-environmental-behaviors-and-well-being.-Young-Consumers-ahead-of-printahead-of-print..pdf\">estudo<\/a>n\u00e3o coincidiram com os resultados do Concordia sobre os benef\u00edcios dos produtos verdes. Uma pesquisa com quase 1.000 jovens adultos americanos constatou que comprar menos est\u00e1 relacionado ao aumento do bem-estar pessoal e \u00e0 diminui\u00e7\u00e3o do sofrimento psicol\u00f3gico.<\/p>\n\n\n\n<p>Portanto, em vez de adquirir mais bens materiais &#8211; embora &#8220;verdes&#8221; -, talvez dev\u00eassemos tentar reduzir nosso consumo geral.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O custo de comprar verde<\/strong><\/h2>\n\n\n\n<p>Embora comprar menos seja inerentemente melhor para o bolso, comprar verde talvez n\u00e3o seja. Os itens ecol\u00f3gicos geralmente s\u00e3o mais caros do que seus equivalentes menos sustent\u00e1veis. De fato, para a maioria dos consumidores, o pre\u00e7o \u00e9 a <a href=\"https:\/\/ssir.org\/articles\/entry\/cultivating_the_green_consumer\">maior barreira<\/a> para a compra de produtos ecol\u00f3gicos.<\/p>\n\n\n\n<p>\u00c9 importante considerar, no entanto, as raz\u00f5es por tr\u00e1s dessa diferen\u00e7a de pre\u00e7o. <a href=\"https:\/\/hbr.org\/2019\/07\/the-elusive-green-consumer\">A demanda<\/a> por produtos verdes ainda est\u00e1 aqu\u00e9m dos produtos tradicionais, o que aumenta os pre\u00e7os. O cultivo e a fabrica\u00e7\u00e3o de materiais sustent\u00e1veis tamb\u00e9m <a href=\"https:\/\/www.fao.org\/organicag\/oa-faq\/oa-faq5\/en\/\">custam mais<\/a>, especialmente se forem utilizadas pr\u00e1ticas \u00e9ticas e padr\u00f5es de trabalho justos. Al\u00e9m de tudo isso, as certifica\u00e7\u00f5es de terceiros, como <a href=\"https:\/\/www.fairtradeamerica.org\/for%20business\/How-to-get-certified\">com\u00e9rcio justo<\/a> e <a href=\"https:\/\/www.thebalancesmb.com\/how-much-does-organic-certification-cost-2538018\">org\u00e2nico<\/a>, n\u00e3o s\u00e3o baratas.<\/p>\n\n\n\n<p>Como consumidores, muitas vezes olhamos para uma etiqueta de pre\u00e7o e vemos esse n\u00famero como o custo total de nossa compra. Esquecemo-nos das externalidades, ou danos, pelos quais n\u00e3o pagamos, pelo menos n\u00e3o com nossas contas banc\u00e1rias. De fato, pagamos por esses danos de forma oculta, <a href=\"https:\/\/www.profoodworld.com\/home\/article\/13275851\/identifying-the-cost-of-sustainable-farming\">alerta<\/a> Patrick Holden, diretor executivo da Sustainable Food Trust, no Reino Unido. Quando voc\u00ea leva em conta a degrada\u00e7\u00e3o ambiental e os efeitos negativos sobre a sa\u00fade p\u00fablica resultantes de nossas pr\u00e1ticas de produ\u00e7\u00e3o atuais e altamente insustent\u00e1veis, come\u00e7a a perceber que os custos de nossos produtos v\u00e3o muito al\u00e9m do pre\u00e7o. E <em>n\u00f3s &#8211; jovens<\/em>consumidores e gera\u00e7\u00f5es futuras &#8211; pagaremos o pre\u00e7o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ent\u00e3o, voc\u00ea deve comprar verde ou comprar menos?<\/strong><\/h2>\n\n\n\n<p>N\u00e3o h\u00e1 uma resposta clara. O problema pode estar na pergunta. N\u00e3o podemos escolher entre comprar verde e comprar menos. Devemos fazer as duas coisas.<\/p>\n\n\n\n<p>Da pr\u00f3xima vez que voc\u00ea quiser comprar aquele novo par de t\u00eanis de corrida, pergunte a si mesmo se os do ano passado podem durar um pouco mais. Comprando menos, voc\u00ea ter\u00e1 mais dinheiro no bolso.<\/p>\n\n\n\n<p>Mas n\u00e3o se sinta culpado por comprar para voc\u00ea ou para seus entes queridos um bom presente fora das necessidades di\u00e1rias. \u00c0s vezes, voc\u00ea merece um novo par de cal\u00e7as de ioga. Voc\u00ea deve simplesmente tentar encontrar marcas que limitem os danos ambientais e sociais associados \u00e0 produ\u00e7\u00e3o. Para obter orienta\u00e7\u00e3o sobre como fazer isso, o World Wide Fund for Nature e outras organiza\u00e7\u00f5es oferecem algumas <a href=\"https:\/\/wwf.panda.org\/get_involved\/live_green\/out_shopping\/\">dicas \u00fateis<\/a>. Embora possam custar mais no in\u00edcio, muitos produtos ecologicamente corretos economizam dinheiro a longo prazo. Por exemplo, roupas feitas com tecido de origem sustent\u00e1vel geralmente duram mais, economizando o dinheiro que voc\u00ea poderia ter gasto com substitui\u00e7\u00f5es frequentes.<\/p>\n\n\n\n<p>Se mais pessoas adotarem essa nova mentalidade dualista, poderemos mudar lentamente nossa mentalidade para reduzir nossos h\u00e1bitos materialistas arraigados. Al\u00e9m de ser mais ecol\u00f3gico e econ\u00f4mico, voc\u00ea tamb\u00e9m ajudar\u00e1 <a href=\"https:\/\/sustainablereview.com\/pt-br\/o-que-acontece-com-as-roupas-doadas\/\">a preservar nosso planeta<\/a>. E voc\u00ea provavelmente ficar\u00e1 muito mais feliz ao perseguir o caloroso brilho de tornar nosso planeta melhor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p>Se voc\u00ea \u00e9 um adulto socialmente consciente, talvez tenha tido problemas para navegar na selva de marcas e ofertas de produtos que \u00e9 o espa\u00e7o ecol\u00f3gico.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Panorama geral<\/strong>: As compras dominam a cultura moderna, mas tamb\u00e9m promovem muitos problemas, como cadeias de suprimentos confusas ou a abund\u00e2ncia de res\u00edduos pl\u00e1sticos no oceano.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Nas entrelinhas<\/strong>: <em>Comprar<\/em> produtos <em>verdes<\/em> ou ecologicamente corretos cria um &#8220;brilho caloroso&#8221; nos consumidores. Isso gera satisfa\u00e7\u00e3o, como a sensa\u00e7\u00e3o de ajudar os outros.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Bolsa vs. Prop\u00f3sito<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li>Comprar menos \u00e9 melhor para o bolso, mas comprar produtos ecol\u00f3gicos nem sempre \u00e9 mais caro.<\/li>\n<li>O pre\u00e7o costuma ser a maior barreira para os consumidores<\/li>\n<li>Os itens ecologicamente corretos geralmente s\u00e3o mais caros do que as alternativas menos sustent\u00e1veis<\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Para as pessoas<\/strong>: Comprar verde ou comprar menos? Resposta curta &#8211; voc\u00ea pode fazer as duas coisas <\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li>Limitar seu consumo dentro do razo\u00e1vel\n<ul>\n<li>De um lado <strong>\u270b:<\/strong> voc\u00ea n\u00e3o precisa parar de comprar coisas de que precisa regularmente, mas talvez n\u00e3o precise daquele quarto par de \u00f3culos de sol<\/li>\n<li>Por outro lado <strong>:<\/strong> talvez voc\u00ea mere\u00e7a aquele novo par de \u00f3culos de sol depois de sua \u00faltima conquista, n\u00f3s entendemos. Incentivamos voc\u00ea a encontrar uma empresa que tenha um impacto ambiental limitado &#8211; Leia como <em>aqui<\/em>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Aprofunde-se \u2192 3 min<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":27,"featured_media":4041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3094],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea \u00e9 um adulto socialmente consciente, talvez tenha tido problemas para navegar na selva de marcas e ofertas de produtos que \u00e9 o espa\u00e7o ecol\u00f3gico.  Panorama geral: As compras dominam a cultura moderna, mas tamb\u00e9m promovem muitos problemas, como cadeias de suprimentos confusas ou a abund\u00e2ncia de res\u00edduos pl\u00e1sticos no oceano.  Nas entrelinhas: Comprar produtos verdes ou ecologicamente corretos cria um &quot;brilho caloroso&quot; nos consumidores. Isso gera satisfa\u00e7\u00e3o, como a sensa\u00e7\u00e3o de ajudar os outros.  Bolsa vs. Prop\u00f3sito  Comprar menos \u00e9 melhor para o bolso, mas comprar produtos ecol\u00f3gicos nem sempre \u00e9 mais caro.O pre\u00e7o costuma ser a maior barreira para os consumidoresOs itens ecologicamente corretos geralmente s\u00e3o mais caros do que as alternativas menos sustent\u00e1veis  Para as pessoas: Comprar verde ou comprar menos? Resposta curta - voc\u00ea pode fazer as duas coisas   Limitar seu consumo dentro do razo\u00e1velDe um lado \u270b: voc\u00ea n\u00e3o precisa parar de comprar coisas de que precisa regularmente, mas talvez n\u00e3o precise daquele quarto par de \u00f3culos de solPor outro lado : talvez voc\u00ea mere\u00e7a aquele novo par de \u00f3culos de sol depois de sua \u00faltima conquista, n\u00f3s entendemos. Incentivamos voc\u00ea a encontrar uma empresa que tenha um impacto ambiental limitado - Leia como aqui.  Aprofunde-se \u2192 3 min\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\" \/>\n<meta property=\"og:site_name\" content=\"Sustainable Review\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T05:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-10T17:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paige Montfort\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:site\" content=\"@sustainreview\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paige Montfort\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\"},\"author\":{\"name\":\"Paige Montfort\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/3fb18ec401a80327c5d5f9ec2b15c564\"},\"headline\":\"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o\",\"datePublished\":\"2020-05-22T05:16:00+00:00\",\"dateModified\":\"2024-08-10T17:13:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\"},\"wordCount\":837,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg\",\"articleSection\":[\"Estilo de vida\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\",\"name\":\"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review\",\"isPartOf\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg\",\"datePublished\":\"2020-05-22T05:16:00+00:00\",\"dateModified\":\"2024-08-10T17:13:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"fast fashion more is less buy green\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/sustainablereview.com\/pt-br\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#website\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"name\":\"Sustainable Review\",\"description\":\"Let us do the &#039;Green-splaining&#039;\",\"publisher\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#organization\",\"name\":\"Sustainable Review\",\"url\":\"https:\/\/sustainablereview.com\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png\",\"width\":800,\"height\":800,\"caption\":\"Sustainable Review\"},\"image\":{\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/sustainreview\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/3fb18ec401a80327c5d5f9ec2b15c564\",\"name\":\"Paige Montfort\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/b244ac8ce3c6de521946d2b7b6f8305e.jpg?ver=1778480760\",\"contentUrl\":\"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/b244ac8ce3c6de521946d2b7b6f8305e.jpg?ver=1778480760\",\"caption\":\"Paige Montfort\"},\"url\":\"https:\/\/sustainablereview.com\/pt-br\/author\/paigem\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/","og_locale":"pt_BR","og_type":"article","og_title":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review","og_description":"Se voc\u00ea \u00e9 um adulto socialmente consciente, talvez tenha tido problemas para navegar na selva de marcas e ofertas de produtos que \u00e9 o espa\u00e7o ecol\u00f3gico.  Panorama geral: As compras dominam a cultura moderna, mas tamb\u00e9m promovem muitos problemas, como cadeias de suprimentos confusas ou a abund\u00e2ncia de res\u00edduos pl\u00e1sticos no oceano.  Nas entrelinhas: Comprar produtos verdes ou ecologicamente corretos cria um \"brilho caloroso\" nos consumidores. Isso gera satisfa\u00e7\u00e3o, como a sensa\u00e7\u00e3o de ajudar os outros.  Bolsa vs. Prop\u00f3sito  Comprar menos \u00e9 melhor para o bolso, mas comprar produtos ecol\u00f3gicos nem sempre \u00e9 mais caro.O pre\u00e7o costuma ser a maior barreira para os consumidoresOs itens ecologicamente corretos geralmente s\u00e3o mais caros do que as alternativas menos sustent\u00e1veis  Para as pessoas: Comprar verde ou comprar menos? Resposta curta - voc\u00ea pode fazer as duas coisas   Limitar seu consumo dentro do razo\u00e1velDe um lado \u270b: voc\u00ea n\u00e3o precisa parar de comprar coisas de que precisa regularmente, mas talvez n\u00e3o precise daquele quarto par de \u00f3culos de solPor outro lado : talvez voc\u00ea mere\u00e7a aquele novo par de \u00f3culos de sol depois de sua \u00faltima conquista, n\u00f3s entendemos. Incentivamos voc\u00ea a encontrar uma empresa que tenha um impacto ambiental limitado - Leia como aqui.  Aprofunde-se \u2192 3 min","og_url":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/","og_site_name":"Sustainable Review","article_published_time":"2020-05-22T05:16:00+00:00","article_modified_time":"2024-08-10T17:13:28+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg","type":"image\/jpeg"}],"author":"Paige Montfort","twitter_card":"summary_large_image","twitter_creator":"@sustainreview","twitter_site":"@sustainreview","twitter_misc":{"Escrito por":"Paige Montfort","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#article","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/"},"author":{"name":"Paige Montfort","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/3fb18ec401a80327c5d5f9ec2b15c564"},"headline":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o","datePublished":"2020-05-22T05:16:00+00:00","dateModified":"2024-08-10T17:13:28+00:00","mainEntityOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/"},"wordCount":837,"commentCount":0,"publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg","articleSection":["Estilo de vida"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/","url":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/","name":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o &#8212; Sustainable Review","isPartOf":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage"},"thumbnailUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg","datePublished":"2020-05-22T05:16:00+00:00","dateModified":"2024-08-10T17:13:28+00:00","breadcrumb":{"@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#primaryimage","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/07\/faubourg-story-fast-fashion-scaled.jpg","width":2560,"height":1707,"caption":"fast fashion more is less buy green"},{"@type":"BreadcrumbList","@id":"https:\/\/sustainablereview.com\/pt-br\/pessoas-menos-e-mais-compras-de-verao-verdes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sustainablereview.com\/pt-br\/inicio\/"},{"@type":"ListItem","position":2,"name":"Menos \u00e9 mais quando voc\u00ea compra verde neste ver\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/sustainablereview.com\/pt-br\/#website","url":"https:\/\/sustainablereview.com\/pt-br\/","name":"Sustainable Review","description":"Let us do the &#039;Green-splaining&#039;","publisher":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sustainablereview.com\/pt-br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sustainablereview.com\/pt-br\/#organization","name":"Sustainable Review","url":"https:\/\/sustainablereview.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/uploads\/2020\/06\/static1.squarespace.png","width":800,"height":800,"caption":"Sustainable Review"},"image":{"@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sustainreview"]},{"@type":"Person","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/3fb18ec401a80327c5d5f9ec2b15c564","name":"Paige Montfort","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sustainablereview.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/b244ac8ce3c6de521946d2b7b6f8305e.jpg?ver=1778480760","contentUrl":"https:\/\/sustainablereview.com\/wp-content\/litespeed\/avatar\/b244ac8ce3c6de521946d2b7b6f8305e.jpg?ver=1778480760","caption":"Paige Montfort"},"url":"https:\/\/sustainablereview.com\/pt-br\/author\/paigem\/"}]}},"wpml_translations":{"en":"3751","pl":"60796","pt-br":"39491"},"_links":{"self":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39491"}],"collection":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39491"}],"version-history":[{"count":2,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39491\/revisions"}],"predecessor-version":[{"id":59279,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/posts\/39491\/revisions\/59279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media\/4041"}],"wp:attachment":[{"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sustainablereview.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}